{"id":1411,"date":"2015-02-05T08:55:43","date_gmt":"2015-02-05T06:55:43","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=1411"},"modified":"2025-12-10T08:58:46","modified_gmt":"2025-12-10T06:58:46","slug":"certificado-de-emision-de-gases","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/","title":{"rendered":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright size-full wp-image-1412\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg\" alt=\"Certificado de emisi\u00f3n de gases\" width=\"300\" height=\"450\" srcset=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases-200x300.jpg 200w, https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Los fabricantes deben realizar unos\u00a0<strong>ensayos homologados<\/strong>, siguiendo la normativa vigente, para lo que deben estar certificados. Los gases que se miden en estos ensayos son los\u00a0<strong>hidrocarburos totales<\/strong>\u00a0(HCT), el\u00a0<strong>mon\u00f3xido de carbono<\/strong>\u00a0(CO) y los\u00a0<strong>\u00f3xidos de nitr\u00f3geno<\/strong>\u00a0(NOx).<\/p>\n<p>Cuando <strong>compres una moto<\/strong>,\u00a0nueva\u00a0o de\u00a0segunda mano, te recomendamos que te asegures de que te entregan el certificado de emisi\u00f3n de gases, pues es un documento que <strong>vas a necesitar cuando lleves tu moto<\/strong> a la revisi\u00f3n t\u00e9cnica del veh\u00edculo.<\/p>\n<h2>La normativa europea de emisi\u00f3n de gases<\/h2>\n<p>Cada vez es\u00a0<strong>m\u00e1s restrictiva<\/strong>\u00a0y est\u00e1 regulada por una directiva europea. Desde el 2014 est\u00e1 en vigor la conocida como\u00a0<strong>Euro 3<\/strong>, aunque tambi\u00e9n est\u00e1n ya previstas las normativas Euro 4 y Euro 5 que entrar\u00e1n en vigor en los a\u00f1os 2017 y 2020, respectivamente.<\/p>\n<p>La\u00a0<a title=\"normativa europea emisi\u00f3n de gases\" href=\"http:\/\/europa.eu\/legislation_summaries\/environment\/air_pollution\/l28186_es.htm\" target=\"_blank\" rel=\"noopener noreferrer\">normativa de emisi\u00f3n de gases<\/a>\u00a0afecta a las\u00a0motos que se fabrican\u00a0en el per\u00edodo en el que est\u00e1 en vigor su correspondiente normativa, por lo que si tu moto ha sido fabricada en a\u00f1os anteriores, su <strong>certificado de emisi\u00f3n de gases<\/strong> puede que se ajuste a las normativas Euro 1 o Euro 2.<\/p>\n<p>Debido a las\u00a0<strong>exigencias medioambientales<\/strong>\u00a0y al\u00a0<strong>desarrollo tecnol\u00f3gico<\/strong>, las sucesivas normas Euro son cada vez m\u00e1s restrictivas. As\u00ed, la normativa Euro 3 impone una <strong>considerable reducci\u00f3n en las emisiones<\/strong> de los tipos de moto L3e y L4e, respecto a la normativa Euro2.<\/p>\n<p>Los\u00a0<strong>niveles m\u00e1ximos<\/strong>\u00a0de CO\u00a0var\u00edan\u00a0de 500 mg\/km de la Euro 2 a 2000 mg\/km en la Euro 3 y los niveles de CO permitidos se reducen a la mitad, pasando de 300 mg\/km a 150 mg\/km. Algo similar ocurre con los <strong>niveles de HCT<\/strong>, pero estos dependen de la cilindrada de la moto.<\/p>\n<h2>El certificado de emisi\u00f3n de gases: documento esencial\u00a0en la ITV<\/h2>\n<p>Los\u00a0<strong>fabricantes<\/strong>\u00a0de tu moto aseguran gracias al certificado de emisi\u00f3n de gases que las medidas realizadas en las <strong>condiciones de la norma,<\/strong>\u00a0son iguales o menores a los valores m\u00e1ximos permitidos en la directiva europea.<\/p>\n<p>El certificado de emisi\u00f3n de gases un <strong>documento de\u00a0vital importancia<\/strong>, pues los l\u00edmites de\u00a0<strong>emisi\u00f3n de CO<\/strong>\u00a0que se analizan en la <a title=\"Claves para pasar la ITV a tu moto\" href=\"consejos-amv\/claves-para-pasar-la-itv-a-tu-moto\/\">inspecci\u00f3n t\u00e9cnica de la moto<\/a> no pueden sobrepasar el valor indicado en dicho certificado.<\/p>\n<ul>\n<li>Si tu moto est\u00e1\u00a0<strong>matriculada antes del 17\/06\/2003<\/strong>\u00a0no dispondr\u00e1s del certificado de emisi\u00f3n de gases, y, en ese caso, el valor permitido para la emisi\u00f3n de CO es del 4.5 en volumen.<\/li>\n<li>Si tu veh\u00edculo est\u00e1 matriculado\u00a0<strong>despu\u00e9s de esa fecha<\/strong>\u00a0y no dispones del certificado, el valor permitido de CO es del 0.5% en volumen. Este\u00a0<strong>puede ser mayor<\/strong>\u00a0que la que establece la norma vigente en el a\u00f1o de fabricaci\u00f3n de tu moto, por lo que es importante que dispongas del <strong>certificado de emisi\u00f3n de gases. <\/strong>La mejor opci\u00f3n es que te pongas en contacto con el\u00a0fabricante de la moto, para que <strong>te facilite un nuevo certificado.<\/strong><\/li>\n<\/ul>\n<p>A veces, es posible que puedas hacer este tr\u00e1mite desde un\u00a0<strong>concesionario<\/strong>. No obstante, te recomendamos que te asegures de disponer de este certificado de emisi\u00f3n de gases en el\u00a0momento de la <a title=\"Consejos para comprar una moto\" href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/consejos-para-comprar-una-moto-clasica\/\">compra de tu moto<\/a> y que lo guardes con toda la documentaci\u00f3n para tenerlo todo a mano.<\/p>\n<p>Cada vez que acudas a realizar la\u00a0<strong>inspecci\u00f3n t\u00e9cnica oficial de la moto<\/strong>, tendr\u00e1s que\u00a0<strong>presentar el certificado <\/strong>de emisi\u00f3n de gases. Las motos est\u00e1n exentas de este tr\u00e1mite hasta que tienen cuatro a\u00f1os de antig\u00fcedad, mientras que los <a title=\"Consejos para comprar un ciclomotor de segunda mano\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/comprar-ciclomotor-segunda-mano\/\">ciclomotores <\/a>est\u00e1n exentos tres a\u00f1os.<\/p>\n<p>A partir de la primera inspecci\u00f3n t\u00e9cnica del veh\u00edculo, las\u00a0<strong>revisiones<\/strong>\u00a0se realizan cada\u00a0<strong>dos a\u00f1os<\/strong>\u00a0en ambos casos, con lo que tu certificado de emisi\u00f3n de gases tendr\u00e1s que presentarlo en todas estas ocasiones. <strong>Es muy importante<\/strong> que mantengas el\u00a0<strong>control peri\u00f3dico<\/strong>\u00a0de las emisiones de tu moto. Acude a tu taller de confianza para revisarla.<\/p>\n<p><em><strong>Tambi\u00e9n puedes leer: <\/strong><\/em><\/p>\n<p><a title=\"Claves para pasar la ITV a tu moto\" href=\"consejos-amv\/claves-para-pasar-la-itv-a-tu-moto\/\"><strong>Claves para pasar la ITV a tu moto<\/strong><\/a><\/p>\n<p><a title=\"Motos el\u00e9ctricas: preguntas frecuentes\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/motos-electricas-preguntas-frecuentes\/\"><strong>Motos el\u00e9ctricas: preguntas frecuentes<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El certificado de emisi\u00f3n de gases es un\u00a0<strong>documento oficial<\/strong>\u00a0emitido por el fabricante de la moto, en el que se asegura el cumplimiento de la <strong>normativa en vigor<\/strong> referida a la\u00a0<strong><a title=\"La moto, una gran alternativa\" href=\"consejos-amv\/la-moto-una-gran-alternativa\/\">emisi\u00f3n de gases contaminantes<\/a>.<\/strong><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[163,164,15,162],"class_list":["post-1411","post","type-post","status-publish","format-standard","hentry","category-noticias-motor","tag-gases","tag-itv","tag-moto","tag-normativa"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV<\/title>\n<meta name=\"description\" content=\"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-05T06:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T06:58:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo AMV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/\"},\"author\":{\"name\":\"Equipo AMV\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\"},\"headline\":\"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta\",\"datePublished\":\"2015-02-05T06:55:43+00:00\",\"dateModified\":\"2025-12-10T06:58:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/\"},\"wordCount\":711,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certificado-de-emision-de-gases.jpg\",\"keywords\":[\"Gases\",\"ITV\",\"Moto\",\"Normativa\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/\",\"name\":\"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certificado-de-emision-de-gases.jpg\",\"datePublished\":\"2015-02-05T06:55:43+00:00\",\"dateModified\":\"2025-12-10T06:58:46+00:00\",\"description\":\"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certificado-de-emision-de-gases.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certificado-de-emision-de-gases.jpg\",\"width\":300,\"height\":450,\"caption\":\"Certificado de emisi\u00f3n de gases\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/certificado-de-emision-de-gases\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\",\"name\":\"Equipo AMV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"caption\":\"Equipo AMV\"},\"description\":\"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/equipo-amv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV","description":"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/","og_locale":"es_ES","og_type":"article","og_title":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV","og_description":"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/","og_site_name":"Blog AMV","article_published_time":"2015-02-05T06:55:43+00:00","article_modified_time":"2025-12-10T06:58:46+00:00","og_image":[{"width":300,"height":450,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg","type":"image\/jpeg"}],"author":"Equipo AMV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/"},"author":{"name":"Equipo AMV","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904"},"headline":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta","datePublished":"2015-02-05T06:55:43+00:00","dateModified":"2025-12-10T06:58:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/"},"wordCount":711,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg","keywords":["Gases","ITV","Moto","Normativa"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/","name":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg","datePublished":"2015-02-05T06:55:43+00:00","dateModified":"2025-12-10T06:58:46+00:00","description":"El certificado de emisi\u00f3n de gases es un documento oficial emitido por el fabricante de la moto,en el que se asegura el cumplimiento de la normativa.","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/10\/certificado-de-emision-de-gases.jpg","width":300,"height":450,"caption":"Certificado de emisi\u00f3n de gases"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/certificado-de-emision-de-gases\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"Certificado de emisi\u00f3n de gases: qu\u00e9 es y c\u00f3mo te afecta"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904","name":"Equipo AMV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","caption":"Equipo AMV"},"description":"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.","url":"https:\/\/www.amv.es\/blog\/author\/equipo-amv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":1,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":6460,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/1411\/revisions\/6460"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}