{"id":1770,"date":"2016-03-21T16:25:55","date_gmt":"2016-03-21T14:25:55","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=1770"},"modified":"2024-10-29T16:33:12","modified_gmt":"2024-10-29T14:33:12","slug":"tipos-de-carnet-de-moto-examenes-practicos","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/","title":{"rendered":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos?"},"content":{"rendered":"<h2><strong>Tipos de carnet de moto: pruebas pr\u00e1cticas<\/strong><\/h2>\n<h3>strong&gt;Carnet AM<\/h3>\n<p>El examen pr\u00e1ctico del carnet AM consiste en la realizaci\u00f3n de dos maniobras consecutivas, tal y como se\u00f1ala la\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/tramites-y-multas\/permiso-de-conduccion\/maniobras\/permiso-am.shtml\">sede electr\u00f3nica de la DGT<\/a>:<\/p>\n<ul>\n<li><strong>Primera maniobra<\/strong>: Partiendo de la posici\u00f3n en parado y en primera velocidad, el aspirante debe pasar entre una franja de anchura limitada sin tocar los bordes ni perder el equilibrio. Esta franja estar\u00e1 delimitada por cualquier se\u00f1al visible que permita detectar si el aspirante ha sobrepasado sus l\u00edmites.<\/li>\n<li><strong>Segunda maniobra<\/strong>: Continuando en primera relaci\u00f3n de marchas, el aspirante debe realizar un zig-zag entre cinco jalones (el primero ha de pasarse por la derecha), no estando permitido arrollarlos ni salirse de la zona delimitada.<\/li>\n<\/ul>\n<h3><span id=\"Carnet_A1\" class=\"ez-toc-section\"><\/span><strong>Carn<\/strong><strong>et A1<\/strong><\/h3>\n<p>El examen pr\u00e1ctico del carnet A1 consta de dos pruebas: una en circuito cerrado y otra en v\u00edas abiertas el tr\u00e1fico. Comenzamos por el\u00a0<strong>examen en circuito cerrado<\/strong>, una prueba que consta de tres partes:<\/p>\n<ul>\n<li><strong>Manejo de la moto en parado<\/strong>: Con la moto apagada y usando nuestra propia fuerza, hay que realizar una maniobra marcha atr\u00e1s para colocar la moto en el rect\u00e1ngulo y prepararse para comenzar la prueba de obst\u00e1culos.<\/li>\n<li><strong>Sorteo de obst\u00e1culos<\/strong>: Se debe circular entre una franja de anchura limitada y sortear 5 jalones. Se tiene que acelerar hasta 30 km.\/h. y meter segunda velocidad, para despu\u00e9s frenar de forma controlada y dentro de los l\u00edmites marcados.<\/li>\n<li><strong>Recorrido cronometrado<\/strong>: Hay que acelerar en la recta y encarar el primer obst\u00e1culo, sortear 5 conos (el primero ha de pasarse por la izquierda). Acto seguido se hace un cambio de direcci\u00f3n sorteando un obst\u00e1culo y se encara la recta de vuelta. Ahora enfrentamos un cambio de trazada pasando entre conos amarillos. Finalmente, nos detenemos en la zona delimitada. Todo este recorrido ha de realizarse en un tiempo m\u00e1ximo de 25 segundos. Si sobrepasamos ese tiempo l\u00edmite, el examen estar\u00e1 suspenso aunque no hayamos cometido un solo fallo m\u00e1s.<\/li>\n<\/ul>\n<p>Por su parte, el\u00a0<strong>examen en v\u00edas abiertas al tr\u00e1fico<\/strong>\u00a0consiste en circular por el recorrido indicado por el examinador respetando las normas y se\u00f1ales del c\u00f3digo de circulaci\u00f3n. El aspirante ir\u00e1 seguido por un veh\u00edculo en el que viajar\u00e1n su profesor y el examinador, que se comunicar\u00e1 con \u00e9l a trav\u00e9s de un intercomunicador. El alumno debe demostrar que est\u00e1 preparado para circular en condiciones de tr\u00e1fico normales. La duraci\u00f3n de esta prueba ronda los 15-20 minutos.<\/p>\n<h3><strong>;Carnet A2<\/strong><\/h3>\n<p>Las pruebas pr\u00e1cticas para obtener el\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/carnet-a2-motos\/\">carnet A2<\/a>\u00a0son las mismas que para obtener el permiso A1. Si tenemos el carnet A1 con m\u00e1s de dos a\u00f1os de antig\u00fcedad tan solo ser\u00e1 necesario realizar el examen de circulaci\u00f3n en v\u00edas abiertas al tr\u00e1fico.<\/p>\n<h3><strong>Carnet A<\/strong><\/h3>\n<p>Para obtener el carnet A no hay que superar ning\u00fan tipo de examen, ni te\u00f3rico ni pr\u00e1ctico. Se necesita tener m\u00e1s de dos a\u00f1os de antig\u00fcedad con el carnet A2 y\u00a0<strong>superar una formaci\u00f3n de 9 horas<\/strong>, distribuida en 3 horas te\u00f3ricas y\u00a0<strong>6 horas pr\u00e1cticas<\/strong>. A su vez, la formaci\u00f3n pr\u00e1ctica se reparte entre 4 horas en circuito cerrado y 2 horas en v\u00edas abiertas al tr\u00e1fico.<\/p>\n<p>La formaci\u00f3n pr\u00e1ctica se debe realizar en\u00a0<strong>motos de cilindrada igual o superior a 600 c.c. y, al menos, 40 kW de potencia<\/strong>. El aspirante debe llevar un equipo formado por casco integral, botas, guantes, cazadora y pantalones de moto. Asimismo, para la formaci\u00f3n en v\u00edas abiertas al tr\u00e1fico el alumno deber\u00e1 llevar un chaleco reflectante con la letra \u201cP\u201d (\u201cPr\u00e1cticas\u201d) a la espalda.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><strong><em>Tambi\u00e9n te puede interesar<\/em><\/strong>:<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/todos-los-tipos-de-carnet-de-conducir-para-moto\/\">Todos los tipos de carnet de conducir para moto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los ex\u00e1menes pr\u00e1cticos que debes pasar para obtener los distintos tipos de carnet de moto: AM, A1, A2 y A.<\/p>\n","protected":false},"author":3,"featured_media":1772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[203,15,79],"class_list":["post-1770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-motor","tag-carnet","tag-moto","tag-reglamento"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV<\/title>\n<meta name=\"description\" content=\"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-21T14:25:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T14:33:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"641\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo AMV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/\"},\"author\":{\"name\":\"Equipo AMV\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\"},\"headline\":\"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos?\",\"datePublished\":\"2016-03-21T14:25:55+00:00\",\"dateModified\":\"2024-10-29T14:33:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/tipos-de-carnet-de-moto.jpg\",\"keywords\":[\"Carnet\",\"Moto\",\"Reglamento\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/\",\"name\":\"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/tipos-de-carnet-de-moto.jpg\",\"datePublished\":\"2016-03-21T14:25:55+00:00\",\"dateModified\":\"2024-10-29T14:33:12+00:00\",\"description\":\"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/tipos-de-carnet-de-moto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/tipos-de-carnet-de-moto.jpg\",\"width\":641,\"height\":427,\"caption\":\"Tipos de carnet de moto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/tipos-de-carnet-de-moto-examenes-practicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\",\"name\":\"Equipo AMV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"caption\":\"Equipo AMV\"},\"description\":\"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/equipo-amv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV","description":"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/","og_locale":"es_ES","og_type":"article","og_title":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV","og_description":"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/","og_site_name":"Blog AMV","article_published_time":"2016-03-21T14:25:55+00:00","article_modified_time":"2024-10-29T14:33:12+00:00","og_image":[{"width":641,"height":427,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg","type":"image\/jpeg"}],"author":"Equipo AMV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/"},"author":{"name":"Equipo AMV","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904"},"headline":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos?","datePublished":"2016-03-21T14:25:55+00:00","dateModified":"2024-10-29T14:33:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg","keywords":["Carnet","Moto","Reglamento"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/","name":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg","datePublished":"2016-03-21T14:25:55+00:00","dateModified":"2024-10-29T14:33:12+00:00","description":"Aqu\u00ed puedes encontrar toda la informaci\u00f3n sobre los ex\u00e1menes pr\u00e1cticos de los distintos tipos de carnet de moto AM, A1, A2 y A. \u00a1Descubre aqu\u00ed la info!","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2016\/03\/tipos-de-carnet-de-moto.jpg","width":641,"height":427,"caption":"Tipos de carnet de moto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/tipos-de-carnet-de-moto-examenes-practicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"Tipos de carnet de moto: \u00bfc\u00f3mo son los ex\u00e1menes pr\u00e1cticos?"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904","name":"Equipo AMV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","caption":"Equipo AMV"},"description":"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.","url":"https:\/\/www.amv.es\/blog\/author\/equipo-amv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/1770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=1770"}],"version-history":[{"count":0,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/1770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/1772"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=1770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=1770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=1770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}