{"id":2237,"date":"2019-01-28T13:09:51","date_gmt":"2019-01-28T11:09:51","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=2237"},"modified":"2025-03-13T18:55:09","modified_gmt":"2025-03-13T16:55:09","slug":"calendario-provisional-motogp-2019-comienza-la-competicion","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/","title":{"rendered":"Calendario MotoGP 2019"},"content":{"rendered":"<p>Ya se han concretado las fechas de la pr\u00f3xima temporada del Campeonato del Mundo de MotoGP.<\/p>\n<p>El calendario seguir\u00e1 contando con 19 pruebas, y como siempre, la cita inicial ser\u00e1 en Gran Premio de Qatar y la cita final el Gran Premio de Valencia.<\/p>\n<h2>Calendario MotoGP 2019: estas son las 19 pruebas<\/h2>\n<p>A continuaci\u00f3n, te indicamos las fechas de las carreras del calendario de MotoGP 2019.<\/p>\n<ul>\n<li>10 de marzo \u2013 Gran Premio de Qatar \u2013 Losail International Circuit<\/li>\n<li>31 de marzo \u2013 Gran Premio de Argentina \u2013 Circuito de Termas de R\u00edo Hondo<\/li>\n<li>14 de abril \u2013 Gran Premio de las Am\u00e9ricas \u2013 Circuit of the Americas<\/li>\n<li>5 de mayo \u2013 Gran Premio de Espa\u00f1a \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>19 de mayo \u2013 Gran Premio de Francia \u2013 Circuito de Le Mans<\/li>\n<li>2 de junio \u2013 Gran Premio de Italia \u2013 Autodromo del Mugello<\/li>\n<li>16 de junio \u2013 Gran Premio de Catalunya \u2013 Circuit de Barcelona \u2013 Catalunya<\/li>\n<li>30 de junio \u2013 Gran Premio de Holanda \u2013 TT Circuit Assen<\/li>\n<li>7 de julio \u2013 Gran Premio de Alemania \u2013 Sachsenring Circuit<\/li>\n<li>4 de agosto \u2013 Gran Premio de la Rep\u00fablica Checa \u2013 Automotodrom Brno<\/li>\n<li>11 de agosto \u2013 Gran Premio de Austria \u2013 Red Bull Ring \u2013 Spielberg<\/li>\n<li>25 de agosto \u2013 Gran Premio de Inglaterra \u2013 Silverstone Circuit<\/li>\n<li>15 de septiembre \u2013 Gran Premio de San Marino \u2013 Misano World Circuit Marco Simoncelli<\/li>\n<li>22 de septiembre \u2013 Gran Premio de Arag\u00f3n \u2013 Motorland Arag\u00f3n<\/li>\n<li>6 de octubre \u2013 Gran Premio de Tailandia \u2013 Chang International Circuit<\/li>\n<li>20 de octubre \u2013 Gran Premio de Jap\u00f3n \u2013 Twin Ring Motegi<\/li>\n<li>27 de octubre \u2013 Gran Premio de Australia \u2013 Phillip Island Circuit<\/li>\n<li>3 de noviembre \u2013 Gran Premio de Malasia \u2013 Sepang International Circuit<\/li>\n<li>17 de noviembre \u2013 Gran Premio de la Comunitat Valenciana \u2013 Circuit Ricardo Tormo<\/li>\n<\/ul>\n<h2>Calendario de test de la temporada 2019<\/h2>\n<p>A continuaci\u00f3n os indicamos las fechas de los test de pretemporada y oficiales para cada una de las categor\u00edas:<\/p>\n<ul>\n<li>6 de febrero \u2013 Test de MotoGP \u2013 Sepang International Circuit<\/li>\n<li>20 de febrero \u2013 Test de Moto2 y Moto3 \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>23 de febrero \u2013 Test de MotoGP \u2013 Losail International Circuit<\/li>\n<li>1 de marzo \u2013 Test de Moto2 y Moto3 \u2013 Losail International Circuit<\/li>\n<li>12 de marzo \u2013 Test de MotoE \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>23 de abril \u2013 Test de MotoE \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>6 de mayo \u2013 Test de MotoGP \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>7 de mayo \u2013 Test Moto2 y Moto3 \u2013 Circuito de Jerez \u2013 \u00c1ngel Nieto<\/li>\n<li>17 de junio \u2013 Test MotoGP \u2013 Circuit de Barcelona \u2013 Catalunya<\/li>\n<li>18 de junio- Test Moto2 y Moto3 \u2013 Circuit de Barcelona \u2013 Catalunya<\/li>\n<li>5 de agosto \u2013 Test de MotoGP \u2013 Automotodrom Brno<\/li>\n<li>12 de agosto \u2013 Test Moto2 y Moto3 \u2013 Red Bull Ring \u2013 Spielberg<\/li>\n<li>28 de agosto \u2013 Test MotoGP \u2013 Misano World Circuit Marco Simoncelli<\/li>\n<\/ul>\n<h2>Novedades para la temporada 2019<\/h2>\n<p>Este a\u00f1o se han introducido dos novedades principales:<\/p>\n<ol>\n<li>La creaci\u00f3n de la <a href=\"http:\/\/www.motogp.com\/es\/noticias\/2018\/11\/14\/motoe-actualizacion-de-pilotos-y-reglamento\/278351\">Copa del Mundo FIM MotoE<\/a>: Es un campeonato exclusivo para motos el\u00e9ctricas 0 emisiones. Esta temporada se han anunciado 5 citas en 5 circuitos europeos (Jerez, Le Mans, Sachsenring, Spielberg, Misano. Las carreras ser\u00e1n de 10 vueltas y tendr\u00e1s una duraci\u00f3n aproximada de 15 minutos. Se disputar\u00e1n antes de las carreras de Moto3.<\/li>\n<li>Es la primera vez que Triumph ser\u00e1 proveedor oficial de motores en Moto2.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del <strong>calendario MotoGP 2019<\/strong>porque en las pr\u00f3ximas semanas viviremos los test de puesta a punto, y el 8, 9 y 10 de marzo se celebrar\u00e1 la ya m\u00edtica prueba de arranque de temporada en Qatar. \u00bfEst\u00e1s listo para la acci\u00f3n?<\/p>\n","protected":false},"author":3,"featured_media":2238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[39],"class_list":["post-2237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-motogp"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV<\/title>\n<meta name=\"description\" content=\"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-28T11:09:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T16:55:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo AMV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/\"},\"author\":{\"name\":\"Equipo AMV\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\"},\"headline\":\"Calendario MotoGP 2019\",\"datePublished\":\"2019-01-28T11:09:51+00:00\",\"dateModified\":\"2025-03-13T16:55:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/\"},\"wordCount\":491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/calendario-motogp-2019.jpg\",\"keywords\":[\"MotoGP\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/\",\"name\":\"Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/calendario-motogp-2019.jpg\",\"datePublished\":\"2019-01-28T11:09:51+00:00\",\"dateModified\":\"2025-03-13T16:55:09+00:00\",\"description\":\"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/calendario-motogp-2019.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/calendario-motogp-2019.jpg\",\"width\":1200,\"height\":900,\"caption\":\"Calendario Motogp 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/calendario-provisional-motogp-2019-comienza-la-competicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calendario MotoGP 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\",\"name\":\"Equipo AMV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"caption\":\"Equipo AMV\"},\"description\":\"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/equipo-amv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV","description":"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/","og_locale":"es_ES","og_type":"article","og_title":"Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV","og_description":"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.","og_url":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/","og_site_name":"Blog AMV","article_published_time":"2019-01-28T11:09:51+00:00","article_modified_time":"2025-03-13T16:55:09+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg","type":"image\/jpeg"}],"author":"Equipo AMV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/"},"author":{"name":"Equipo AMV","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904"},"headline":"Calendario MotoGP 2019","datePublished":"2019-01-28T11:09:51+00:00","dateModified":"2025-03-13T16:55:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/"},"wordCount":491,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg","keywords":["MotoGP"],"articleSection":["Eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/","url":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/","name":"Calendario MotoGP 2019: comienza la competici\u00f3n | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg","datePublished":"2019-01-28T11:09:51+00:00","dateModified":"2025-03-13T16:55:09+00:00","description":"\u00bfNecesitas que vuelva ya MotoGP? \u00a1Tranquilo! La temporada 2019 est\u00e1 a punto de dar el pistoletazo de salida. Toma nota de las fechas del calendario MotoGP.","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/calendario-motogp-2019.jpg","width":1200,"height":900,"caption":"Calendario Motogp 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/eventos\/calendario-provisional-motogp-2019-comienza-la-competicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.amv.es\/blog\/eventos\/"},{"@type":"ListItem","position":3,"name":"Calendario MotoGP 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904","name":"Equipo AMV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","caption":"Equipo AMV"},"description":"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.","url":"https:\/\/www.amv.es\/blog\/author\/equipo-amv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=2237"}],"version-history":[{"count":1,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2237\/revisions"}],"predecessor-version":[{"id":5238,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2237\/revisions\/5238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/2238"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=2237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=2237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=2237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}