{"id":2325,"date":"2019-05-21T10:21:21","date_gmt":"2019-05-21T08:21:21","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=2325"},"modified":"2026-03-18T14:50:08","modified_gmt":"2026-03-18T12:50:08","slug":"que-hacer-en-caso-de-accidente-de-moto","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/","title":{"rendered":"\u00bfQu\u00e9 hacer en caso de accidente de moto?"},"content":{"rendered":"<p>Sin duda, son muchos los aspectos importantes a tener en cuenta en caso de sufrir o presenciar un\u00a0<strong>accidente de moto<\/strong>. Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!<\/p>\n<h2><strong>Equipamiento motero: nuestra seguridad pasiva<\/strong><\/h2>\n<p>M\u00e1s vale prevenir que curar. \u00bfLo has escuchado alguna vez? De ah\u00ed la importancia que adquiere el equipamiento motero, nuestra seguridad pasiva. Ante la probabilidad de sufrir un\u00a0<strong>accidente de moto<\/strong>, lo primero que debemos hacer es equiparnos correctamente. \u00a1Y en cualquier \u00e9poca del a\u00f1o!<\/p>\n<p>En moto no tenemos una carrocer\u00eda que nos proteja ni un cintur\u00f3n de seguridad que nos sujete. Por ello es tan importante el uso de un\u00a0<a href=\"https:\/\/www.amv.escomo-saber-si-un-casco-de-moto-esta-homologado\/\">casco homologado<\/a>\u00a0y de complementos con protecciones como chaqueta, pantal\u00f3n,\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/blog\/opiniones\/guantes-de-moto-esenciales-para-la-seguridad\/\">guantes<\/a>\u00a0y botas. En un\u00a0<strong>accidente de moto<\/strong>, pueden minimizar las consecuencias y, en el caso del casco, salvarnos la vida.<\/p>\n<p>Despreciar la ayuda de estos elementos de seguridad es una actitud negligente e irresponsable. Solamente por utilizar el casco, la probabilidad de sufrir una lesi\u00f3n grave se reduce un 25%. Y el factor de protecci\u00f3n del resto de complementos es muy superior al de las prendas \u201cde calle\u201d. \u00a1No lo olvides!<\/p>\n<h3><strong>\u00bfEl calor influye en los accidentes de moto?<\/strong><\/h3>\n<p>As\u00ed es. Los meses m\u00e1s calurosos del a\u00f1o son cr\u00edticos. En la \u00e9poca estival, el n\u00famero de abrasiones y rozaduras que sufren los motoristas se incrementa un 47%. Est\u00e1 claro: son muchos quienes, en lugar de ir bien equipados, prefieren desplazarse en moto utilizando una camiseta de manga corta, unos bermudas y hasta unas chanclas\u2026<\/p>\n<p>Para prevenir las consecuencias de un\u00a0<strong>accidente de moto<\/strong>,\u00a0<a href=\"https:\/\/www.amv.esequipamiento-motero-en-verano-no-te-la-juegues\/\">\u00a1equ\u00edpate bien en verano!<\/a>\u00a0En el mercado encontrar\u00e1s cascos y complementos dise\u00f1ados para hacer frente a las altas temperaturas. \u00bfC\u00f3mo quieres pasar el verano? \u00bfDisfrutando de tu moto con el equipamiento adecuado o en un centro m\u00e9dico cur\u00e1ndote las lesiones sufridas por circular con pantal\u00f3n corto? \u00a1Pi\u00e9nsalo!<\/p>\n<h2><strong>Declaraci\u00f3n amistosa de accidente: \u00a1no nos enfademos!<\/strong><\/h2>\n<p>Si hemos sufrido un\u00a0<strong>accidente de moto<\/strong>\u00a0en el que ha estado implicado otro veh\u00edculo, enfadarse y mostrarse agresivo no lleva a ning\u00fan camino. Por dicho motivo, lo mejor es conservar la calma y actuar de forma coherente.<\/p>\n<p>Si el\u00a0<strong>accidente de moto<\/strong>\u00a0ha sido leve, procederemos a rellenar el\u00a0<a href=\"https:\/\/www.amv.es\/blog\/guias-amv\/como-rellenar-un-parte-amistoso-de-accidente\/\">parte amistoso<\/a>. Es la mejor opci\u00f3n y nos ahorrar\u00e1 muchos problemas posteriores. Si no tienes muy claro c\u00f3mo hay que hacerlo, te animamos a que le eches un vistazo a la declaraci\u00f3n amistosa de accidente que debes llevar junto a los\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/papeles-y-documentacion-que-debes-llevar-en-tu-moto-para-no-ser-multado\/\">papeles de la moto<\/a>. Y en el supuesto de que carezcas de ella, p\u00eddesela a tu compa\u00f1\u00eda aseguradora o mediador de seguros. En caso de accidente:<\/p>\n<ul>\n<li>Si es una colisi\u00f3n entre dos veh\u00edculos, utiliza solamente un formulario.<\/li>\n<li>Ver\u00e1s que hay dos columnas: una para el conductor A y otra para el B. La que elijas debe llevar todos tus datos. \u00a1No mezcles informaci\u00f3n de los dos conductores en la misma columna!<\/li>\n<li>Rellena los campos con claridad: tus datos personales, si hay heridos, c\u00f3mo se producido el accidente, los datos del seguro, etc.<\/li>\n<li>Tambi\u00e9n tendr\u00e1s que hacer un croquis del accidente. No hace falta recrearse en el dibujo. Cuanto m\u00e1s sencillo y comprensible sea, mejor.<\/li>\n<li>Por \u00faltimo, los conductores deber\u00e9is firmar el parte y quedaros cada uno con una copia.<\/li>\n<li>Y si se te ha olvidado algo, no te preocupes. En la parte de atr\u00e1s de la declaraci\u00f3n hay m\u00e1s campos que podr\u00e1s rellenar en casa o en la oficina de la compa\u00f1\u00eda aseguradora.<\/li>\n<\/ul>\n<p>\u00a1Ah! Si no llevas el parte amistoso de accidente entre los papeles de la moto, no te preocupes. La aplicaci\u00f3n\u00a0<a class=\"broken_link\" href=\"https:\/\/declaracionidea.es\/iDEAWebPublica\/inicio.do\">Declaraci\u00f3n iDEA<\/a>\u00a0te facilitar\u00e1 rellenarlo desde tu tel\u00e9fono m\u00f3vil. \u00a1Sencillo y r\u00e1pido!<\/p>\n<h3><strong>\u00bfC\u00f3mo actuar en caso de presenciar un accidente de moto?<\/strong><\/h3>\n<p>Si presenciamos un\u00a0<strong>accidente de moto<\/strong>, la forma de actuar variar\u00e1 mucho en funci\u00f3n de d\u00f3nde y c\u00f3mo se haya producido el siniestro. Y tambi\u00e9n de las consecuencias. Pero, por norma general, lo primero que deberemos hacer es asegurar la zona, es decir, evitar que se produzca otro accidente con consecuencias peores. Algo que, por desgracia, sucede bastantes veces.<\/p>\n<p>Tras un accidente de tr\u00e1fico, por peque\u00f1o que sea, hay un momento de aturdimiento en el que actuamos de forma impulsiva y desordenada. En muchos casos, ocupando partes de la calzada en las que podemos correr un riesgo. En lugar de andar de un lado a otro sin saber muy bien c\u00f3mo actuar, hay que tranquilizarse y poner en pr\u00e1ctica el\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/territorio-amv\/consejos-amv\/ID\/104\/que-es-el-protocolo-pas-y-para-que-sirve\">Protocolo PAS<\/a>\u00a0(Proteger, Avisar y Socorrer).<\/p>\n<ul>\n<li><strong>Proteger.<\/strong>\u00a0Este paso consiste en apartar todo aquello que estorba en la v\u00eda. Si no fuese posible, se tratar\u00e1 de se\u00f1alizar los obst\u00e1culos para que otros conductores se percaten de la situaci\u00f3n.<\/li>\n<li><strong>Avisar.<\/strong>\u00a0A continuaci\u00f3n, en caso necesario, se ha de avisar a los equipos de emergencia. En Espa\u00f1a, el n\u00famero de tel\u00e9fono al que se debe llamar es el 112. Ten en cuenta que te pedir\u00e1n informaci\u00f3n y que la misma tiene que ser muy clara respecto a las personas implicadas, el lugar del accidente, los veh\u00edculos siniestrados, etc. No hay que ponerse nervioso al hablar con el operador para no retrasar la llegada de la ayuda.<\/li>\n<li><strong>Socorrer.<\/strong>\u00a0Por \u00faltimo, hay que prestar atenci\u00f3n a las v\u00edctimas. Al hablar con el 112, sus profesionales nos indicar\u00e1n qu\u00e9 debemos hacer. Es esencial seguir sus instrucciones, ya que la manipulaci\u00f3n incorrecta de un herido puede dar lugar a consecuencias fatales.<\/li>\n<\/ul>\n<h3><strong>\u00bfY si el accidente de moto es grave?<\/strong><\/h3>\n<p>Tras se\u00f1alizar la situaci\u00f3n \u2013si vas en coche, utiliza tus tri\u00e1ngulos de emergencia y ponte el chaleco reflectante\u2013, hay que ocuparse de las v\u00edctimas. Muchos conductores no saben qu\u00e9 hacer si presencian un\u00a0<strong>accidente de moto<\/strong>.<\/p>\n<p>Como hemos comentado, mover o manipular a un accidentado es algo muy serio y complejo. \u00a1Y en el caso de los motoristas, m\u00e1s a\u00fan! En el 112 te dir\u00e1n qu\u00e9 hay que hacer. Y como principio b\u00e1sico, no trates de quitarle el casco al accidentado, ya que podr\u00edas agravar las lesiones.<\/p>\n<h2><strong>Paso a paso: qu\u00e9 hacer en caso de accidente de moto<\/strong><\/h2>\n<p>Si sufres o presencias un\u00a0<strong>accidente de moto<\/strong>, te recordamos los pasos m\u00e1s importantes que han de ponerse en pr\u00e1ctica:<\/p>\n<ul>\n<li>Siempre que sea posible, los veh\u00edculos implicados en un accidente de tr\u00e1fico o que se hayan detenido para socorrer a los heridos han de encontrarse en un lugar seguro. El objetivo es no entorpecer la circulaci\u00f3n y evitar que se produzcan m\u00e1s accidentes.<\/li>\n<li>Si sufrimos un\u00a0<strong>accidente de moto<\/strong>\u00a0en el que haya estado implicado otro veh\u00edculo, debemos rellenar el parte amistoso (bien en papel, bien mediante la aplicaci\u00f3n Declaraci\u00f3n iDEA).<\/li>\n<li><a class=\"broken_link\" href=\"https:\/\/www.amv.es\/territorio-amv\/consejos-amv\/ID\/1144\/senalizar-un-accidente--triangulos-de-senalizacion-y-chalecos-reflectantes\">Se\u00f1alizar el lugar del accidente<\/a>. Los motoristas no est\u00e1n obligados a llevar tri\u00e1ngulos. Pero si vamos en coche, hay que colocarlos correctamente en la calzada. Y para movernos en ella, tendremos que usar el chaleco reflectante.<\/li>\n<li>Apartar los objetos que haya en la calzada y puedan resultar peligrosos.<\/li>\n<li>Avisar a los equipos de emergencia llamando al n\u00famero de tel\u00e9fono 112 y a la compa\u00f1\u00eda aseguradora en caso necesario.<\/li>\n<li>Seguir las indicaciones de los profesionales del 112 para atender a las v\u00edctimas. Si est\u00e1n conscientes, a los heridos se les debe transmitir tranquilidad.<\/li>\n<li>Y una vez que lleguen las asistencias, seguiremos sus indicaciones.<\/li>\n<\/ul>\n<p>Confiamos en que no sufras o presencies un\u00a0<strong>accidente de moto<\/strong>. Pero si te ves implicado en una situaci\u00f3n as\u00ed, estos consejos te ser\u00e1n de gran ayuda.<\/p>\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-blog-de-motos-y-noticias-del-sector\">\n<div class=\"wp-block-embed__wrapper\"><iframe class=\"wp-embedded-content lazyloaded\" title=\"\u00ab\u00bfCu\u00e1les son las causas m\u00e1s frecuentes de los accidentes de moto?\u00bb \u2014 Blog de motos y noticias del sector\" src=\"consejos-amv\/cuales-son-las-causas-mas-frecuentes-de-los-accidentes-de-moto\/embed\/#?secret=GOjzrAbxrx\" width=\"600\" height=\"287\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-scripts\" data-src=\"consejos-amv\/cuales-son-las-causas-mas-frecuentes-de-los-accidentes-de-moto\/embed\/#?secret=GOjzrAbxrx\" data-secret=\"GOjzrAbxrx\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/figure>\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-blog-de-motos-y-noticias-del-sector\">\n<div class=\"wp-block-embed__wrapper\"><iframe class=\"wp-embedded-content lazyloaded\" title=\"\u00ab\u00bfC\u00f3mo evitar accidentes en moto? Consejos para evitarlos\u00bb \u2014 Blog de motos y noticias del sector\" src=\"consejos-amv\/como-evitar-accidentes-en-moto\/embed\/#?secret=J0u81SSTQi\" width=\"600\" height=\"308\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-scripts\" data-src=\"consejos-amv\/como-evitar-accidentes-en-moto\/embed\/#?secret=J0u81SSTQi\" data-secret=\"J0u81SSTQi\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sin duda, son muchos los aspectos importantes a tener en cuenta en caso de sufrir o presenciar un\u00a0<strong>accidente de moto<\/strong>. Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!<\/p>\n","protected":false},"author":2,"featured_media":2326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[28,15,80],"class_list":["post-2325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-amv","tag-accidente","tag-moto","tag-seguridad"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20200220"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV<\/title>\n<meta name=\"description\" content=\"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-21T08:21:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T12:50:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"\u00bfQu\u00e9 hacer en caso de accidente de moto?\",\"datePublished\":\"2019-05-21T08:21:21+00:00\",\"dateModified\":\"2026-03-18T12:50:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/\"},\"wordCount\":1327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Consejos-accidente-moto.jpeg\",\"keywords\":[\"Accidente\",\"Moto\",\"Seguridad\"],\"articleSection\":[\"Consejos AMV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/\",\"name\":\"\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Consejos-accidente-moto.jpeg\",\"datePublished\":\"2019-05-21T08:21:21+00:00\",\"dateModified\":\"2026-03-18T12:50:08+00:00\",\"description\":\"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Consejos-accidente-moto.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Consejos-accidente-moto.jpeg\",\"width\":800,\"height\":533,\"caption\":\"Consejos AMV en accidente de moto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-hacer-en-caso-de-accidente-de-moto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 hacer en caso de accidente de moto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV","description":"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV","og_description":"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!","og_url":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/","og_site_name":"Blog AMV","article_published_time":"2019-05-21T08:21:21+00:00","article_modified_time":"2026-03-18T12:50:08+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"\u00bfQu\u00e9 hacer en caso de accidente de moto?","datePublished":"2019-05-21T08:21:21+00:00","dateModified":"2026-03-18T12:50:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/"},"wordCount":1327,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg","keywords":["Accidente","Moto","Seguridad"],"articleSection":["Consejos AMV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/","url":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/","name":"\u00bfQu\u00e9 hacer en caso de accidente de moto? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg","datePublished":"2019-05-21T08:21:21+00:00","dateModified":"2026-03-18T12:50:08+00:00","description":"Desde c\u00f3mo rellenar el parte amistoso hasta la manera adecuada de atender a los heridos, te lo explicamos todo en el presente post. \u00a1Sigue leyendo!","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Consejos-accidente-moto.jpeg","width":800,"height":533,"caption":"Consejos AMV en accidente de moto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-hacer-en-caso-de-accidente-de-moto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos AMV","item":"https:\/\/www.amv.es\/blog\/consejos-amv\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 hacer en caso de accidente de moto?"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=2325"}],"version-history":[{"count":1,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2325\/revisions"}],"predecessor-version":[{"id":7013,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2325\/revisions\/7013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/2326"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=2325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=2325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=2325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}