{"id":2615,"date":"2024-03-17T12:49:19","date_gmt":"2024-03-17T10:49:19","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=2615"},"modified":"2024-11-10T13:05:28","modified_gmt":"2024-11-10T11:05:28","slug":"mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/","title":{"rendered":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N"},"content":{"rendered":"<p>En la jornada sabatina se disputaron las mangas de clasificaci\u00f3n de \u00c9liteMX1 y \u00c9liteMX2 con las\u00a0<strong>victorias de Jos\u00e9 Antonio Butr\u00f3n y David Braceras<\/strong>, respectivamente, que se hicieron con las\u00a0<strong>Poles AMV.<\/strong>\u00a0Adem\u00e1s, tambi\u00e9n se llevaron a cabo las primeras mangas de MX125 donde\u00a0<strong>Salvi P\u00e9rez no tuvo rival y de MXFemenino con Daniela Guill\u00e9n como protagonista<\/strong>.<\/p>\n<p><a class=\"broken_link\" href=\"https:\/\/www.youtube.com\/watch?v=h4vsQT3Q4nM\">Pincha aqu\u00ed<\/a>\u00a0para ver de nuevo toda la acci\u00f3n de hoy en el canal de Youtube de la RFME.<\/p>\n<h2 class=\"wp-block-heading\">Butr\u00f3n, sin rival en \u00c9liteMX1<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2617 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/Butron_CE_MX_Malpartida_2024-600x400.jpg\" alt=\"Butron_CE_MX_Malpartida_2024\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Xurxo Prol ha sido el que mejor ha salido<\/strong>\u00a0en la primera manga de la m\u00e1xima categor\u00eda pero ha tenido problemas mec\u00e1nicos y ha abandonado. Jos\u00e9 Antonio Butr\u00f3n, que se hab\u00eda puesto segundo tras la salida,\u00a0<strong>ha cogido el liderato para imponer un ritmo alt\u00edsimo<\/strong>\u00a0y ganar con autoridad. Ander Valent\u00edn ha rodado segundo tambi\u00e9n distanciado de Sime\u00f3 Ubach, tercero.<\/p>\n<p>En la parte de arriba\u00a0<strong>las posiciones ya no han cambiado<\/strong>\u00a0y as\u00ed es como ha finalizado la manga.<\/p>\n<p>La segunda ha tenido a\u00a0<strong>Butr\u00f3n y a Valent\u00edn delante sin que nadie m\u00e1s<\/strong>\u00a0pudiera acercarse a ellos. Han sido los dos que mejor ritmo han tenido y han disfrutado y\u00a0<strong>hecho disfrutar a los aficionados<\/strong>\u00a0que han llenado las instalaciones extreme\u00f1as.<\/p>\n<p>Por detr\u00e1s\u00a0<strong>Sime\u00f3 Ubach y Nil Arcarons han peleado<\/strong>\u00a0por la tercera posici\u00f3n intercambi\u00e1ndose el puesto en m\u00e1s de una ocasi\u00f3n pero ha sido Ubach el que lo ha logrado.<\/p>\n<p>La\u00a0<strong>Placa 24MX sigue en manos de Jos\u00e9 Antonio Butr\u00f3n<\/strong>\u00a0una carrera m\u00e1s.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Braceras_gana_Congost_placa_roja_24MX_de_EliteMX2\" class=\"ez-toc-section\"><\/span>Braceras gana. Congost, placa roja 24MX de \u00c9liteMX2<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2618 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-Barceras-600x400.jpg\" alt=\"MXMalpartida_domingo_2024-Barceras\" width=\"600\" height=\"400\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La primera manga de \u00c9liteMX2 ha sido impresionante.\u00a0<strong>El\u00edas Escandell ha salido primero y se ha mantenido en esa posici\u00f3n<\/strong>\u00a0durante gran parte de las vueltas, pero han pasado muchas cosas que han hecho cambiar todas las posiciones.\u00a0<strong>Segundo ha rodado Samuel Nilsson<\/strong>\u00a0logrando mantener ese puesto hasta la llegada de algunos de sus rivales. David Beltr\u00e1n ha estado en P3 hasta que, remontando desde atr\u00e1s, David Braceras lo ha superado.<\/p>\n<p>Poco a poco,\u00a0<strong>Samuel ha ido acerc\u00e1ndose a El\u00edas<\/strong>\u00a0pero es que David ha hecho lo propio y no solo ha adelantado a Samuel sino que\u00a0<strong>tambi\u00e9n ha pasado a El\u00edas<\/strong>. El final ha sido s\u00faper emocionante con\u00a0<strong>Gerard Congost llegando hasta el de Fantic<\/strong>\u00a0y cruzando la meta casi en paralelo.<\/p>\n<p>Remontada tambi\u00e9n muy buena la del\u00a0<strong>piloto del equipo nacional RFME, Fran Garc\u00eda<\/strong>, que se ha ca\u00eddo en la salida y tras quedarse \u00faltimo, ha terminado sexto.<\/p>\n<p>Finalmente,\u00a0<strong>David Braceras ha ganado<\/strong>, Gerard Congost ha sido segundo y El\u00edas Escandell tercero.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2619 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-2--600x400.jpg\" alt=\"MXMalpartida_domingo_2024-2-\" width=\"600\" height=\"400\" \/><\/p>\n<p>En la segunda\u00a0<strong>Braceras se ha puesto en cabeza desde el inicio<\/strong>\u00a0con El\u00edas, Adri\u00e0 Monn\u00e9, Gerard y Fran detr\u00e1s.\u00a0<strong>Mala suerte para Samuel Nilsson<\/strong>\u00a0que se ha ca\u00eddo en la salida y, aunque ha querido continuar y ha hecho dos vueltas, se ha tenido que retirar.<\/p>\n<p>Al contrario que en la primera manga,\u00a0<strong>en \u00e9sta las cosas han sido mucho m\u00e1s tranquilas<\/strong>\u00a0y, tanto David como El\u00edas, han mantenido sus puestos y sin peligro de que nadie se lo arrebatara.\u00a0<strong>No as\u00ed Monn\u00e9 que, a falta de 7 minutos m\u00e1s dos vueltas, ha visto como Congost<\/strong>\u00a0de acercaba peligrosamente a \u00e9l. Tanto es as\u00ed que el de Gas Gas\u00a0<strong>lo ha pasado pero despu\u00e9s se ha ca\u00eddo<\/strong>\u00a0y el de KTM TRT Motorcycle ha recuperado la P3. Aunque no todo iba a quedar ah\u00ed y es que<strong>\u00a0Congost ha superado de nuevo a Adri\u00e0<\/strong>\u00a0y visto la bandera a cuadros tras David y El\u00edas.<\/p>\n<p>En el p\u00f3dium han estado estos tres mismos pilotos y en el mismo orden. Despu\u00e9s de esta carrera, la\u00a0<strong>placa roja 24MX es para Gerard Congost<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Repartidos_Holeshot_REDD_Michelin_TRT_Motorcycle_el_mejor_en_la_REDD_Challenge_NGK\" class=\"ez-toc-section\"><\/span>Repartidos Holeshot REDD Michelin. TRT Motorcycle, el mejor en la REDD Challenge NGK<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2620 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-600x400.jpg\" alt=\"Braceras-MXMalpartida_domingo_2024\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Xurxo Prol se ha llevado el Holeshot REDD Michelin<\/strong>\u00a0en la primera manga de \u00c9liteMX1 y\u00a0<strong>Jos\u00e9 Antonio Butr\u00f3n en la segunda<\/strong>. En\u00a0<strong>\u00c9liteMX2 Pablo Guti\u00e9rrez y Joe Brokkes<\/strong>\u00a0han sido los due\u00f1os de este premio.<\/p>\n<p>El equipo ganador de la\u00a0<strong>REDD Challenge NGK<\/strong>\u00a0de Malpartida ha sido\u00a0<strong>KTM TRT Motorcycle.<\/strong><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Nuevo_doblete_de_Salvador_Perez_en_MX125\" class=\"ez-toc-section\"><\/span>Nuevo doblete de Salvador P\u00e9rez en MX125<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2621 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024_-600x400.jpg\" alt=\"MXMalpartida_domingo_2024_\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Juan Izaguirre ha conseguido rodar en cabeza<\/strong>\u00a0durante los primeros giros pero Salvi P\u00e9rez, que est\u00e1 a otro nivel en la categor\u00eda,\u00a0<strong>ha ido recuperando posiciones<\/strong>\u00a0despu\u00e9s de una salida regular, y lo ha pasado.\u00a0<strong>Valentino V\u00e1zquez, Gon\u00e7alo Lopes y Enzo Badenas\u00a0<\/strong>han completado el top 5 hasta el ecuador de la manga ya que\u00a0<strong>Carlos Prat y Carlos Salvador<\/strong>\u00a0han ido remontando posiciones hasta meterse entre los primeros.<\/p>\n<p>Finalmente,\u00a0<strong>detr\u00e1s de Salvi han cruzado la meta Prat segundo e Izaguirre tercero<\/strong>\u00a0pero al p\u00f3dium han subido Salvador P\u00e9rez, Carlos Prat y Valentino V\u00e1zquez.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Daniela_Guillen_vence_en_MXFemenino\" class=\"ez-toc-section\"><\/span>Daniela Guill\u00e9n vence en MXFemenino<\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2622 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-35-600x400.jpg\" alt=\"MXMalpartida_domingo_2024-Daniela Guillen\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong>Daniela Guill\u00e9n ha vuelto a ser la gran destacada<\/strong>\u00a0en la segunda manga de MX Femenino. Desde la salida\u00a0<strong>ha impuesto su ritmo con la mirada puesta ya en la semana que viene<\/strong>\u00a0donde se celebrar\u00e1 la primera prueba del WMX en Madrid. Jana S\u00e1nchez, que tambi\u00e9n estar\u00e1 en Xanad\u00fa, ha terminado segunda y Aitana Pe\u00f1a tercera.<\/p>\n<p>Las\u00a0<strong>tres han estado en el p\u00f3dium<\/strong>\u00a0como las mejores en Malpartida.<\/p>\n<h2 class=\"wp-block-heading\">Pablo Guti\u00e9rrez se lleva el Best Whip AMV<\/h2>\n<h2 class=\"wp-block-heading\"><span id=\"Pablo_Gutierrez_se_lleva_el_Best_Whip_AMV\" class=\"ez-toc-section\"><\/span><img decoding=\"async\" class=\"aligncenter wp-image-2623 size-fusion-600\" src=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/RFME_CE_MX_Malpartida_2024_Pablo-600x400.jpg\" alt=\"Pablo Guti\u00e9rrez RFME_CE_MX_Malpartida\n\" width=\"600\" height=\"400\" \/><\/h2>\n<p>Con las votaciones muy ajustadas a trav\u00e9s del Instagram de la RFME (@rfme_oficial),\u00a0<strong>Pablo Guti\u00e9rrez ha sido el ganador del Best Whip AMV<\/strong>\u00a0en Las Arenas. Adem\u00e1s,\u00a0<strong>Roger Oliver, que fue el m\u00e1s votado de Lugo<\/strong>, tambi\u00e9n ha recibido el cheque que lo acredita como tal.<\/p>\n<p><strong>Ambos han estado en el p\u00f3dium<\/strong>\u00a0contentos por ser los mejores y llevarse este premio gracias al\u00a0<strong>apoyo de los aficionados en las Redes Sociales<\/strong>.<\/p>\n<p><a class=\"broken_link\" href=\"https:\/\/www.instagram.com\/reel\/C4lI9FKtsEd\/?igsh=cXcxN2Y1ejlhbWhp\">Aqu\u00ed puedes ver las incre\u00edbles plegadas de los pilotos.<\/a><\/p>\n<p>La pr\u00f3xima prueba del\u00a0<strong>Campeonato de Espa\u00f1a de Motocross<\/strong>\u00a0con las categor\u00edas \u00c9lite se celebrar\u00e1 en\u00a0<strong>Sanl\u00facar de Barrameda<\/strong>, C\u00e1diz, el fin de semana del\u00a0<strong>20 y 21 de abril<\/strong>.<\/p>\n<p>Fuente del texto RFME y Fotograf\u00edas Juan Pablo Acevedo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cuarta prueba del\u00a0<strong>Campeonato de Espa\u00f1a de Motocross<\/strong>\u00a0se ha disputado durante este fin de semana en Malpartida de C\u00e1ceres con un ambiente excepcional,\u00a0<strong>mucho p\u00fablico y un sol\u00a0<\/strong>que ya se echaba de menos despu\u00e9s de las carreras de Lugo y Montearag\u00f3n que fueron pasadas por agua.<\/p>\n","protected":false},"author":3,"featured_media":2616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[65,56,52],"class_list":["post-2615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-motociclismo","tag-motocross","tag-mx"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20240611"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"La cuarta prueba del\u00a0Campeonato de Espa\u00f1a de Motocross\u00a0se ha disputado durante este fin de semana en Malpartida de C\u00e1ceres con un ambiente excepcional,\u00a0mucho p\u00fablico y un sol\u00a0que ya se echaba de menos despu\u00e9s de las carreras de Lugo y Montearag\u00f3n que fueron pasadas por agua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-17T10:49:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-10T11:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo AMV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/\"},\"author\":{\"name\":\"Equipo AMV\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\"},\"headline\":\"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N\",\"datePublished\":\"2024-03-17T10:49:19+00:00\",\"dateModified\":\"2024-11-10T11:05:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/\"},\"wordCount\":1060,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MXMalpartida_domingo_2024-12-.jpg\",\"keywords\":[\"Motociclismo\",\"Motocross\",\"MX\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/\",\"name\":\"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MXMalpartida_domingo_2024-12-.jpg\",\"datePublished\":\"2024-03-17T10:49:19+00:00\",\"dateModified\":\"2024-11-10T11:05:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MXMalpartida_domingo_2024-12-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/MXMalpartida_domingo_2024-12-.jpg\",\"width\":1200,\"height\":800,\"caption\":\"MXMalpartida_domingo_2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\",\"name\":\"Equipo AMV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"caption\":\"Equipo AMV\"},\"description\":\"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/equipo-amv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/","og_locale":"es_ES","og_type":"article","og_title":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV","og_description":"La cuarta prueba del\u00a0Campeonato de Espa\u00f1a de Motocross\u00a0se ha disputado durante este fin de semana en Malpartida de C\u00e1ceres con un ambiente excepcional,\u00a0mucho p\u00fablico y un sol\u00a0que ya se echaba de menos despu\u00e9s de las carreras de Lugo y Montearag\u00f3n que fueron pasadas por agua.","og_url":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/","og_site_name":"Blog AMV","article_published_time":"2024-03-17T10:49:19+00:00","article_modified_time":"2024-11-10T11:05:28+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg","type":"image\/jpeg"}],"author":"Equipo AMV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/"},"author":{"name":"Equipo AMV","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904"},"headline":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N","datePublished":"2024-03-17T10:49:19+00:00","dateModified":"2024-11-10T11:05:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/"},"wordCount":1060,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg","keywords":["Motociclismo","Motocross","MX"],"articleSection":["Eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/","url":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/","name":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg","datePublished":"2024-03-17T10:49:19+00:00","dateModified":"2024-11-10T11:05:28+00:00","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/MXMalpartida_domingo_2024-12-.jpg","width":1200,"height":800,"caption":"MXMalpartida_domingo_2024"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/eventos\/mx-malpartida-dobletes-de-butron-braceras-perez-y-guillen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.amv.es\/blog\/eventos\/"},{"@type":"ListItem","position":3,"name":"MX MALPARTIDA: DOBLETES DE BUTR\u00d3N, BRACERAS, P\u00c9REZ Y GUILL\u00c9N"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904","name":"Equipo AMV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","caption":"Equipo AMV"},"description":"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.","url":"https:\/\/www.amv.es\/blog\/author\/equipo-amv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=2615"}],"version-history":[{"count":0,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/2615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/2616"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=2615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=2615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=2615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}