{"id":3562,"date":"2021-09-23T13:21:08","date_gmt":"2021-09-23T11:21:08","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=3562"},"modified":"2026-02-12T15:01:28","modified_gmt":"2026-02-12T13:01:28","slug":"que-carnet-necesitas-para-conducir-una-moto-electrica","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/","title":{"rendered":"\u00bfQu\u00e9 carnet necesitas para conducir una moto el\u00e9ctrica?"},"content":{"rendered":"<p>Poco a poco, las motos el\u00e9ctricas van ganando adeptos. Algo l\u00f3gico porque, como veremos en otro apartado del post, aportan numerosas ventajas a sus usuarios. Sin embargo, muchos conductores a\u00fan no tienen claro cu\u00e1l es el\u00a0<strong>carnet de moto el\u00e9ctrica<\/strong>\u00a0necesario para circular con este tipo de veh\u00edculo.<\/p>\n<p>Conviene saber que el hecho de que sean el\u00e9ctricas no significa que puedan ser conducidas con cualquier carnet. Muy al contrario, al igual que sucede con los impulsados por motor de combusti\u00f3n, cada modelo requiere un permiso de conducci\u00f3n. Si est\u00e1s pensando en adquirir una moto el\u00e9ctrica, \u00a1este art\u00edculo te interesa!<\/p>\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 carnets permiten conducir una moto el\u00e9ctrica?<\/h2>\n<p>En funci\u00f3n de los\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/tipos-de-carnet-de-moto-y-ciclomotor-cuales-hay\/\">tipos de carnet de moto y ciclomotor<\/a>\u00a0existentes, podremos conducir unos modelos el\u00e9ctricos u otros.<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Carnet_AM\" class=\"ez-toc-section\"><\/span>Carnet AM<\/h3>\n<ul>\n<li>El permiso AM autoriza a conducir ciclomotores el\u00e9ctricos cuya velocidad m\u00e1xima, seg\u00fan el\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/buscar\/pdf\/1999\/BOE-A-1999-1826-consolidado.pdf\">Reglamento General de Veh\u00edculos<\/a>, no sea superior a 45 km\/h.<\/li>\n<li>Una de las ventajas del carnet AM es que se puede obtener a partir de 15 a\u00f1os cumplidos. Si tienes esa edad, el permiso de conducci\u00f3n para ciclomotores te facilitar\u00e1 acceder al mundillo motero y adquirir experiencia. \u00a1Toma nota!<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><span id=\"Carnet_A1\" class=\"ez-toc-section\"><\/span>Carnet A1<\/h3>\n<ul>\n<li>Y si has cumplido 16 a\u00f1os podr\u00e1s sacarte el\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/carnet-a1-lo-que-necesitas-saber\/\">carnet A1<\/a>.<\/li>\n<li>En este caso, el\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/buscar\/pdf\/2009\/BOE-A-2009-9481-consolidado.pdf\">Reglamento General de Conductores<\/a>\u00a0establece que el permiso A1 habilita a su titular para conducir motos el\u00e9ctricas con una potencia m\u00e1xima de 11 kW.<\/li>\n<li>Si se trata de triciclos de motor, la potencia no tiene que exceder de 15 kW.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><span id=\"Carnet_A2\" class=\"ez-toc-section\"><\/span>Carnet A2<\/h3>\n<ul>\n<li>El\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/carnet-a2-de-moto-que-hace-falta-para-sacarlo\/\">carnet A2<\/a>\u00a0se ha convertido en otra alternativa interesante para los\u00a0<a href=\"consejos-amv\/las-mejores-motos-para-principiantes\/\">motoristas principiantes<\/a>.<\/li>\n<li>Puede sacarse a partir de 18 a\u00f1os cumplidos.<\/li>\n<li>Y permite conducir motos el\u00e9ctricas m\u00e1s potentes. Concretamente, modelos con una potencia m\u00e1xima de 35 kW.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><span id=\"Carnet_A\" class=\"ez-toc-section\"><\/span>Carnet A<\/h3>\n<ul>\n<li>Para obtener el\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/requisitos-para-obtener-el-permiso-a-de-moto\/\">carnet A<\/a>\u00a0es preciso haber cumplido 20 a\u00f1os y atesorar una experiencia de, al menos, dos a\u00f1os con el carnet A2.<\/li>\n<li>Con el permiso A podremos conducir motos el\u00e9ctricas de cualquier potencia.<\/li>\n<li>Pero si deseamos circular con triciclos el\u00e9ctricos cuya potencia exceda de 15 kW, la normativa exige tener 21 a\u00f1os.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><span id=\"Carnet_B\" class=\"ez-toc-section\"><\/span>Carnet B<\/h3>\n<ul>\n<li>Finalmente, el\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-motos-se-pueden-conducir-con-el-carnet-de-coche\/\">carnet de coche B<\/a>\u00a0es otro\u00a0<strong>carnet de moto el\u00e9ctrica<\/strong>\u00a0a tener en cuenta.<\/li>\n<li>Con \u00e9l es posible conducir ciclomotores el\u00e9ctricos.<\/li>\n<li>Y quienes tengan una antig\u00fcedad superior a tres a\u00f1os con este permiso estar\u00e1n autorizados a circular con los mismos modelos el\u00e9ctricos que pueden manejarse con el carnet A1.<\/li>\n<li>Adem\u00e1s, el carnet B permite conducir triciclos y cuadriciclos el\u00e9ctricos, homologados como tales, de cualquier potencia.<\/li>\n<\/ul>\n<p>Llegados a este punto, es importante recordar que la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/buscar\/pdf\/2015\/BOE-A-2015-11722-consolidado.pdf\">Ley sobre Tr\u00e1fico, Circulaci\u00f3n de Veh\u00edculos a Motor y Seguridad Vial<\/a>\u00a0establece que \u201cconducir un veh\u00edculo careciendo del permiso o licencia de conducci\u00f3n correspondiente\u201d es una infracci\u00f3n grave. Por lo tanto, \u00a1no pretendas conducir una moto el\u00e9ctrica de 35 kW si tienes el carnet A1!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Tipos_de_motos_electricas\" class=\"ez-toc-section\"><\/span>Tipos de motos el\u00e9ctricas<\/h2>\n<p>Una vez repasados los diferentes carnets, \u00bfsabes qu\u00e9 motos el\u00e9ctricas se pueden conducir con ellos? Si no est\u00e1s familiarizado con los veh\u00edculos el\u00e9ctricos, te sorprender\u00e1 saber que su oferta es similar a la de las motos con motor de gasolina.<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Motos_electricas_urbanas\" class=\"ez-toc-section\"><\/span>Motos el\u00e9ctricas urbanas<\/h3>\n<p>Sobre todo, en este grupo encontramos ciclomotores y\u00a0<em>scooters<\/em>\u00a0capaces de satisfacer a todo tipo de usuarios: modelos de rueda baja, alta o de tres ruedas. Y con dise\u00f1o moderno, futurista o retro. \u00a1T\u00fa eliges!<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Motos_electricas_de_carretera\" class=\"ez-toc-section\"><\/span>Motos el\u00e9ctricas de carretera<\/h3>\n<p>Ya sea para itinerarios urbanos o realizar escapadas, los fabricantes tambi\u00e9n comercializan modelos el\u00e9ctricos con est\u00e9tica de moto de carretera. Desde\u00a0<em>naked<\/em>\u00a0o\u00a0<em>streetfighter<\/em>\u00a0hasta\u00a0<em>custom<\/em>\u00a0o\u00a0<em>scrambler<\/em>, abarcan todo tipo de segmentos. Por cierto, \u00bfsab\u00edas que algunas el\u00e9ctricas figuran entre las\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/top-15-motos-deportivas-mas-potentes\/\">motos deportivas m\u00e1s potentes<\/a>\u00a0del planeta?<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Motos_electricas_off_road\" class=\"ez-toc-section\"><\/span>Motos el\u00e9ctricas off road<\/h3>\n<p>Y las marcas tampoco se olvidan del mundo\u00a0<em>off road<\/em>. Si lo tuyo son las motos de tipo\u00a0<em>adventure<\/em>\u00a0o practicar especialidades como el enduro, el\u00a0<em>motocross<\/em>\u00a0o el trial, no te preocupes: hay modelos el\u00e9ctricos que se adaptar\u00e1n a tus necesidades.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Ventajas_de_conducir_una_moto_electrica\" class=\"ez-toc-section\"><\/span>Ventajas de conducir una moto el\u00e9ctrica<\/h2>\n<p>Por lo expuesto, ya conoces todo lo relativo al\u00a0<strong>carnet de moto el\u00e9ctrica<\/strong>. Y tambi\u00e9n cu\u00e1les son los modelos que encontrar\u00e1s en los concesionarios. Tan solo nos falta resumirte algunas de las\u00a0<a href=\"https:\/\/www.amv.es\/blog\/opiniones\/10-ventajas-de-las-motos-electricas\/\">ventajas de conducir una moto el\u00e9ctrica<\/a>:<\/p>\n<ol type=\"1\">\n<li>Distintivo ambiental. Las motos el\u00e9ctricas disponen de etiqueta ambiental de 0 emisiones. En las grandes ciudades, dicho distintivo posibilita circular en zonas de bajas emisiones. Y tambi\u00e9n durante episodios de alta contaminaci\u00f3n.<\/li>\n<li>Privilegios en ciudad. Otras ventajas de las motos el\u00e9ctricas en ciudad son el estacionamiento gratuito, la tarifa reducida en zonas reguladas, la autorizaci\u00f3n para circular en carriles especiales, etc. \u00a1Consulta en tu ayuntamiento!<\/li>\n<li>Exenci\u00f3n de algunos impuestos. En el consistorio tambi\u00e9n te informar\u00e1n si tu moto el\u00e9ctrica est\u00e1 exenta del impuesto de tracci\u00f3n mec\u00e1nica. Adem\u00e1s, estos veh\u00edculos no pagan el impuesto de matriculaci\u00f3n ni el IGIC \u2013equivalente al IVA en las Islas Canarias\u2013.<\/li>\n<li>Buena autonom\u00eda. Gracias a las bater\u00edas extra\u00edbles, la autonom\u00eda ha dejado de ser un problema. Y los principales fabricantes est\u00e1n trabajando conjuntamente para promover el uso de bater\u00edas intercambiables.<\/li>\n<li>Menor coste por kil\u00f3metro. En comparaci\u00f3n con una moto de gasolina, el coste por kil\u00f3metro es m\u00e1s econ\u00f3mico en una el\u00e9ctrica. En tu domicilio, para ahorrar en la factura de la luz, procura recargar la bater\u00eda en horario valle (00 a 08 horas a diario y todo el d\u00eda en s\u00e1bados, domingos y festivos).<\/li>\n<li>Ahorro en mantenimiento. A diferencia de las motos de gasolina, las el\u00e9ctricas no deben pasar tantas revisiones. Y sus motores presumen de ser m\u00e1s sencillos y fiables que los de combusti\u00f3n, algo que se traduce en menos aver\u00edas.<\/li>\n<li>Veh\u00edculos ecol\u00f3gicos. Protagonistas de la movilidad sostenible, las motos el\u00e9ctricas generan menos emisiones contaminantes y ac\u00fasticas. De esta forma, contribuyen a crear entornos urbanos m\u00e1s habitables y saludables.<\/li>\n<li>Ideales para la ciudad. Como las de gasolina, las motos el\u00e9ctricas, por dimensiones y agilidad, son perfectas para los desplazamientos urbanos. Y una alternativa segura al transporte p\u00fablico.<\/li>\n<li>Ayudas a la adquisici\u00f3n. A trav\u00e9s del Plan Moves o el Plan Renove, las administraciones p\u00fablicas destinan partidas econ\u00f3micas para quienes desean adquirir un veh\u00edculo el\u00e9ctrico o instalar un punto de recarga.<\/li>\n<li>Seguro m\u00e1s econ\u00f3mico. Y en comparaci\u00f3n con un autom\u00f3vil, el seguro obligatorio es m\u00e1s asequible. \u00bfQuieres comprobarlo?\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/seguro-moto\/\/tarificar\/#at_medium=display&amp;at_campaign=306&amp;at_creation=que_carnet_necesitas_para_conducir_una_moto_electrica&amp;at_variant=Calcula_ahora_tu_precio_para_el_seguro_de_moto_electrica&amp;at_format=TextLink&amp;at_channel=noticias_amv_es&amp;at_general_placement=&amp;at_detail_placement=\">Calcula ahora tu precio para el seguro de moto el\u00e9ctrica<\/a>. \u00a1Y contrata en solo 3 minutos!<\/li>\n<\/ol>\n<p>Hasta aqu\u00ed, nuestro post dedicado al\u00a0<strong>carnet de moto el\u00e9ctrica<\/strong>. Antes de adquirir un modelo el\u00e9ctrico y al hacer el <a href=\"https:\/\/www.amv.es\/blog\/guias-amv\/retrofit-convertir-moto-de-gasolina-a-electrica\/\">retrofit de una moto<\/a>, aseg\u00farate de tener el permiso adecuado. Y despu\u00e9s, no olvides contratar un seguro obligatorio. \u00a1Bienvenido a la movilidad sostenible!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No existe un\u00a0<strong>carnet de moto el\u00e9ctrica<\/strong>\u00a0espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. Si est\u00e1s interesado en la movilidad sostenible, \u00a1sigue leyendo!<\/p>\n","protected":false},"author":2,"featured_media":3563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[203,128,15],"class_list":["post-3562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-motor","tag-carnet","tag-electrica","tag-moto"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20210914"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV<\/title>\n<meta name=\"description\" content=\"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-23T11:21:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T13:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"\u00bfQu\u00e9 carnet necesitas para conducir una moto el\u00e9ctrica?\",\"datePublished\":\"2021-09-23T11:21:08+00:00\",\"dateModified\":\"2026-02-12T13:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/\"},\"wordCount\":1203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/carnet-moto-electrica.jpeg\",\"keywords\":[\"Carnet\",\"El\u00e9ctrica\",\"Moto\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/\",\"name\":\"\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/carnet-moto-electrica.jpeg\",\"datePublished\":\"2021-09-23T11:21:08+00:00\",\"dateModified\":\"2026-02-12T13:01:28+00:00\",\"description\":\"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/carnet-moto-electrica.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/carnet-moto-electrica.jpeg\",\"width\":850,\"height\":567,\"caption\":\"Qu\u00e9 carnet necesitas para la moto el\u00e9ctrica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/que-carnet-necesitas-para-conducir-una-moto-electrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 carnet necesitas para conducir una moto el\u00e9ctrica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV","description":"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV","og_description":"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/","og_site_name":"Blog AMV","article_published_time":"2021-09-23T11:21:08+00:00","article_modified_time":"2026-02-12T13:01:28+00:00","og_image":[{"width":850,"height":567,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"\u00bfQu\u00e9 carnet necesitas para conducir una moto el\u00e9ctrica?","datePublished":"2021-09-23T11:21:08+00:00","dateModified":"2026-02-12T13:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/"},"wordCount":1203,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg","keywords":["Carnet","El\u00e9ctrica","Moto"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/","name":"\u00bfQu\u00e9 carnet necesitas para conducir moto el\u00e9ctrica? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg","datePublished":"2021-09-23T11:21:08+00:00","dateModified":"2026-02-12T13:01:28+00:00","description":"No existe un carnet de moto el\u00e9ctrica espec\u00edfico. En funci\u00f3n del tipo de veh\u00edculo que vayas a conducir, necesitar\u00e1s un permiso u otro. + info aqu\u00ed:","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/carnet-moto-electrica.jpeg","width":850,"height":567,"caption":"Qu\u00e9 carnet necesitas para la moto el\u00e9ctrica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/que-carnet-necesitas-para-conducir-una-moto-electrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 carnet necesitas para conducir una moto el\u00e9ctrica?"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=3562"}],"version-history":[{"count":2,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3562\/revisions"}],"predecessor-version":[{"id":6796,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3562\/revisions\/6796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/3563"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=3562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=3562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=3562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}