{"id":3694,"date":"2021-04-12T12:43:00","date_gmt":"2021-04-12T10:43:00","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=3694"},"modified":"2025-12-17T17:19:54","modified_gmt":"2025-12-17T15:19:54","slug":"como-averiguar-si-tiene-multas-una-moto-de-segunda-mano","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/","title":{"rendered":"C\u00f3mo averiguar si tiene multas una moto de segunda mano antes de comprarla"},"content":{"rendered":"<p>En muchos casos,\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/comprar-una-moto-de-segunda-mano\/\">comprar una moto de segunda mano<\/a>\u00a0puede ser una buena opci\u00f3n. Sobre todo si quien la vende es un establecimiento de confianza o un motorista conocido que la ha cuidado bien. En cualquier caso, antes de adquirirla conviene saber si existen\u00a0<strong>multas de la moto de segunda mano<\/strong>\u00a0u otro tipo de cargas.<\/p>\n<p>Al respecto, desde la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.dgt.es\/es\/\">Direcci\u00f3n General de Tr\u00e1fico (DGT)<\/a>\u00a0recomiendan obtener un informe de un veh\u00edculo de segunda mano antes de comprarlo. De esta manera, el interesado podr\u00e1 comprobar la existencia de embargos, precintos, procedimientos concursales u otro tipo de cargas de naturaleza administrativa o judicial.<\/p>\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo s\u00e9 si una moto de segunda mano tiene cargas?<\/strong><\/h2>\n<p>Para saber si existen\u00a0<strong>multas de una moto de segunda mano<\/strong>\u00a0u otro tipo de cargas, la DGT facilita solicitar informes que incluyen informaci\u00f3n p\u00fablica de un veh\u00edculo.<\/p>\n<p>Aqu\u00ed te indicamos c\u00f3mo ver si una moto tiene una deuda:<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Informe_reducido\" class=\"ez-toc-section\"><\/span><strong>Informe reducido<\/strong><\/h3>\n<p>El informe reducido es la primera opci\u00f3n para saber si una moto de segunda mano tiene multas o cargas. Y para obtenerlo solamente se necesita conocer la matr\u00edcula o el n\u00famero de bastidor del veh\u00edculo. Ventajas: se trata de un informe gratuito. Inconvenientes: los datos que ofrece son escasos.<\/p>\n<p>Un informe reducido nos dice cu\u00e1l es la fecha de la primera matriculaci\u00f3n en Espa\u00f1a de la moto que deseamos comprar. Y tambi\u00e9n nos indica si hay alguna incidencia que impedir\u00eda la transferencia del veh\u00edculo o su circulaci\u00f3n. Este informe presenta un indicador de color verde y otro rojo:<\/p>\n<ul>\n<li>El indicador de color verde significa que en la DGT no consta ninguna incidencia sobre la moto que se quiere comprar.<\/li>\n<li>Por el contrario, el indicador rojo advierte de alguna situaci\u00f3n irregular. Pero no la especifica.<\/li>\n<\/ul>\n<p>Independientemente del resultado (verde o rojo), si vamos a adquirir un veh\u00edculo de segunda mano lo mejor es solicitar un informe completo. Como revela su denominaci\u00f3n, incluye m\u00e1s informaci\u00f3n y, por lo tanto, es mucho m\u00e1s detallado que el informe reducido.<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Informe_completo\" class=\"ez-toc-section\"><\/span><strong>Informe completo<\/strong><\/h3>\n<p>Concretamente, un informe completo incluye toda la informaci\u00f3n administrativa, identificaci\u00f3n del titular, municipio donde est\u00e1 domiciliada la moto, historial de la\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/defectos-de-tu-moto-a-corregir-para-pasar-la-itv\/\">Inspecci\u00f3n T\u00e9cnica de Veh\u00edculos (ITV)<\/a>, kilometraje, n\u00famero de titulares, cargas, etc. Y tambi\u00e9n datos t\u00e9cnicos, la puntuaci\u00f3n del test EuroNCAP (programa que eval\u00faa la seguridad de los coches nuevos) y la informaci\u00f3n sobre el mantenimiento del veh\u00edculo solicitado.<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Informe_de_datos_tecnicos\" class=\"ez-toc-section\"><\/span><strong>Informe de datos t\u00e9cnicos<\/strong><\/h3>\n<p>Igualmente, la DGT brinda la posibilidad de solicitar un informe con datos b\u00e1sicos de identificaci\u00f3n de la moto. Adem\u00e1s, incluye informaci\u00f3n t\u00e9cnica del veh\u00edculo como potencia, combustible, masas m\u00e1ximas, el historial de la ITV, el resultado de las pruebas EuroNCAP (en el caso de los autom\u00f3viles), etc.<\/p>\n<h3 class=\"wp-block-heading\"><span id=\"Informe_de_cargas\" class=\"ez-toc-section\"><\/span><strong>Informe de cargas<\/strong><\/h3>\n<p>Por \u00faltimo, aunque las cargas se reflejan en el informe completo, en la DGT se puede pedir un informe espec\u00edfico. Junto a los datos b\u00e1sicos de identificaci\u00f3n del veh\u00edculo, este documento refleja las cargas o limitaciones que constan en el Registro de Veh\u00edculos y afectan a un cambio de titularidad.<\/p>\n<p>Ahora que sabes c\u00f3mo ver si una moto tiene una deuda, a continuaci\u00f3n te explicamos c\u00f3mo solicitar los informes en la DGT.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"%C2%BFComo_pueden_solicitarse_los_informes_de_la_DGT\" class=\"ez-toc-section\"><\/span><strong>\u00bfC\u00f3mo pueden solicitarse los informes de la DGT?<\/strong><\/h2>\n<p>Si piensas comprar una moto de segunda mano, podr\u00e1s solicitar los informes por Internet, por tel\u00e9fono, a trav\u00e9s de la aplicaci\u00f3n\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/appmidgt\/\">miDGT<\/a>\u00a0o presencialmente.<\/p>\n<ul>\n<li>Por Internet en la\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/\">sede electr\u00f3nica de la DGT<\/a>. Si eliges esta opci\u00f3n tendr\u00e1s que contar con un certificado digital o estar dado de alta en\u00a0<a class=\"broken_link\" href=\"https:\/\/clave.gob.es\/clave_Home\/clave.html\">Cl@ve<\/a>. Como coment\u00e1bamos anteriormente, el informe reducido es gratuito. Para solicitar un informe detallado (completo, de datos t\u00e9cnicos o de cargas) es preciso\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/otros-tramites\/pago-de-tasas\/index.shtml\">abonar una tasa<\/a>\u00a0de 8,59 euros por informe.<\/li>\n<li>Por tel\u00e9fono. Excepto el reducido, llamando al n\u00famero de tel\u00e9fono 060 es posible solicitar cualquier informe detallado. Previamente, habr\u00e1 que pagar la tasa correspondiente en la sede electr\u00f3nica de la DGT.<\/li>\n<li>Aplicaci\u00f3n miDGT. Gracias a la\u00a0<em>app<\/em>\u00a0gratuita para\u00a0<em>smartphones<\/em>\u00a0y\u00a0<em>tablets<\/em>\u00a0de la DGT se pueden consultar los informes reducido y completo.<\/li>\n<li>Presencialmente. Y otra opci\u00f3n es acudir a una\u00a0<a class=\"broken_link\" href=\"https:\/\/www.dgt.es\/es\/la-dgt\/quienes-somos\/estructura-organica\/jefaturas-provinciales\/\">jefatura u oficina de Tr\u00e1fico<\/a>. \u00a1No olvides\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/otros-tramites\/cita-previa-jefaturas\/index.shtml\">solicitar cita previa por Internet<\/a>\u00a0o llamando al n\u00famero de tel\u00e9fono 060!<\/li>\n<\/ul>\n<p>Si necesitas ampliar informaci\u00f3n, en la subsecci\u00f3n\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.dgt.gob.es\/es\/vehiculos\/informe-de-vehiculo\/index.shtml\">Informe de un veh\u00edculo<\/a>\u00a0de la sede electr\u00f3nica de la DGT encontrar\u00e1s m\u00e1s detalles. Como, por ejemplo, qui\u00e9n est\u00e1 autorizado a realizar los tr\u00e1mites o c\u00f3mo se puede pagar la tasa. Adem\u00e1s, se ha habilitado un apartado reservado a preguntas frecuentes.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Solicitud_de_informe_en_el_Registro_de_Bienes_Muebles\" class=\"ez-toc-section\"><\/span><strong>Solicitud de informe en el Registro de Bienes Muebles<\/strong><\/h2>\n<p>Como habr\u00e1s visto, la DGT nos ayuda a saber si existen\u00a0<strong>multas de una moto de segunda mano<\/strong>\u00a0u otro tipo de cargas. Pero, adem\u00e1s, es recomendable solicitar un informe al\u00a0<a class=\"broken_link\" href=\"https:\/\/www.registradores.org\/\">Registro de Bienes Muebles<\/a>.<\/p>\n<p>Ya sea en calidad de abonado o mediante un certificado digital, accediendo al\u00a0<a class=\"broken_link\" href=\"https:\/\/sede.registradores.org\/site\/\">registro\u00a0<em>online<\/em><\/a>\u00a0de su p\u00e1gina web tambi\u00e9n podremos saber si el veh\u00edculo que queremos adquirir est\u00e1 embargado \u2013por ejemplo, porque su propietario no ha pagado multas de tr\u00e1fico\u2013. O si tiene pagos pendientes, una\u00a0<a href=\"noticias-motor\/que-es-la-reserva-de-dominio-de-un-coche\/\">reserva de dominio<\/a>\u00a0de una entidad financiera o un contrato de\u00a0<em>leasing<\/em>\u00a0que no ha concluido.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Consejos_para_comprar_una_moto_de_segunda_mano\" class=\"ez-toc-section\"><\/span><strong>Consejos para comprar una moto de segunda mano<\/strong><\/h2>\n<p>En definitiva, antes de comprar una moto de segunda mano es importante saber si hay multas de tr\u00e1fico o recibos de financiaci\u00f3n pendientes de pago, si est\u00e1 sujeta a un contrato de\u00a0<em>leasing<\/em>\u00a0activo, si ha sido precintada, si se encuentra al d\u00eda en lo relativo al impuesto municipal de circulaci\u00f3n\u2026<\/p>\n<p>Hasta que no lo tengas claro, lo mejor es que no tomes decisiones precipitadas. Y junto a todo lo expuesto, en el blog ofrecemos los mejores <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/comprar-una-moto-de-segunda-mano\/\">consejos para comprar una moto de segunda mano<\/a>. Entre ellos:<\/p>\n<ol>\n<li>Inf\u00f3rmate sobre la moto que quieres comprar. En p\u00e1ginas web especializadas, clubes de propietarios o foros podr\u00e1s conocer todo lo referente a sus caracter\u00edsticas, venta de recambios, aver\u00edas m\u00e1s frecuentes, etc.<\/li>\n<li>La oferta de motos de segunda mano es amplia y variada. Procura elegir un vendedor (establecimiento o particular) que te transmita confianza.<\/li>\n<li>Si optas por un particular y no entiendes de mec\u00e1nica, solicita probar la moto y que su estado y kilometraje sean revisados por un mec\u00e1nico experto.<\/li>\n<li>Negocia el precio si durante la prueba de la moto has detectado alguna anomal\u00eda. Y tambi\u00e9n si el mec\u00e1nico observa que es necesario sustituir piezas o realizar alguna reparaci\u00f3n.<\/li>\n<li>Exige al vendedor que demuestre que todos los papeles est\u00e1n en regla. Y que no existen\u00a0<strong>multas de la moto de segunda mano<\/strong>\u00a0ni otro tipo de cargas. Solicitar un informe completo a la DGT y una nota informativa al Registro de Bienes Muebles te permitir\u00e1 comprobar si est\u00e1 todo en orden.<\/li>\n<li>Si llegas a un acuerdo con el vendedor, formaliza un contrato de compraventa. Y no hagas ning\u00fan desembolso econ\u00f3mico por adelantado. Lo suyo es que la entrega de la moto y el pago sean simult\u00e1neos. Y que te entreguen una factura por dicho concepto.<\/li>\n<li>En caso de adquirir una moto de segunda mano en un establecimiento, aseg\u00farate de que la garant\u00eda de un a\u00f1o queda reflejada en un documento.<\/li>\n<li>Y si deseas ahorrar tiempo y papeleo, delega los tr\u00e1mites de cambio de titularidad de la moto en los profesionales de una gestor\u00eda.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Antes de comprar una moto de segunda mano es importante saber si tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 \u00bfNo tienes claro c\u00f3mo ver si una moto tiene una deuda? Tranquilo, te lo explicamos en este post. \u00a1Sigue leyendo!<\/p>\n","protected":false},"author":3,"featured_media":3695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[147,15,14,308],"class_list":["post-3694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-amv","tag-comprar","tag-moto","tag-segunda-mano","tag-tramites"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20210520"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV<\/title>\n<meta name=\"description\" content=\"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-12T10:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T15:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo AMV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/\"},\"author\":{\"name\":\"Equipo AMV\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\"},\"headline\":\"C\u00f3mo averiguar si tiene multas una moto de segunda mano antes de comprarla\",\"datePublished\":\"2021-04-12T10:43:00+00:00\",\"dateModified\":\"2025-12-17T15:19:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/\"},\"wordCount\":1313,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/multas-de-moto-de-segunda-mano.jpeg\",\"keywords\":[\"Comprar\",\"Moto\",\"Segunda mano\",\"Tr\u00e1mites\"],\"articleSection\":[\"Consejos AMV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/\",\"name\":\"\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/multas-de-moto-de-segunda-mano.jpeg\",\"datePublished\":\"2021-04-12T10:43:00+00:00\",\"dateModified\":\"2025-12-17T15:19:54+00:00\",\"description\":\"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/multas-de-moto-de-segunda-mano.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/multas-de-moto-de-segunda-mano.jpeg\",\"width\":850,\"height\":629,\"caption\":\"C\u00f3mo saber si una moto de segunda mano tiene multas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo averiguar si tiene multas una moto de segunda mano antes de comprarla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/6d35c1550bc63400096567b9f314a904\",\"name\":\"Equipo AMV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg\",\"caption\":\"Equipo AMV\"},\"description\":\"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/equipo-amv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV","description":"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV","og_description":"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:","og_url":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/","og_site_name":"Blog AMV","article_published_time":"2021-04-12T10:43:00+00:00","article_modified_time":"2025-12-17T15:19:54+00:00","og_image":[{"width":850,"height":629,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg","type":"image\/jpeg"}],"author":"Equipo AMV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/"},"author":{"name":"Equipo AMV","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904"},"headline":"C\u00f3mo averiguar si tiene multas una moto de segunda mano antes de comprarla","datePublished":"2021-04-12T10:43:00+00:00","dateModified":"2025-12-17T15:19:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/"},"wordCount":1313,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg","keywords":["Comprar","Moto","Segunda mano","Tr\u00e1mites"],"articleSection":["Consejos AMV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/","url":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/","name":"\u00bfC\u00f3mo saber si una moto tiene multas o requerimientos pendientes? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg","datePublished":"2021-04-12T10:43:00+00:00","dateModified":"2025-12-17T15:19:54+00:00","description":"Es importante saber si una moto de segunda mano tiene multas, recibos o impuestos pendientes por pagar, si ha sido embargada\u2026 Desc\u00fabrelo aqu\u00ed:","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/multas-de-moto-de-segunda-mano.jpeg","width":850,"height":629,"caption":"C\u00f3mo saber si una moto de segunda mano tiene multas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos AMV","item":"https:\/\/www.amv.es\/blog\/consejos-amv\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo averiguar si tiene multas una moto de segunda mano antes de comprarla"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/6d35c1550bc63400096567b9f314a904","name":"Equipo AMV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-cropped-logo-amv-perfil-noticias-96x96.jpg","caption":"Equipo AMV"},"description":"Somos especialistas en seguros de moto. Aqu\u00ed encontrar\u00e1s todas las novedades y contenidos de inter\u00e9s relacionados con el mundo de las dos ruedas.","url":"https:\/\/www.amv.es\/blog\/author\/equipo-amv\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":2,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3694\/revisions"}],"predecessor-version":[{"id":6580,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3694\/revisions\/6580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/3695"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=3694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=3694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}