{"id":3892,"date":"2020-07-16T12:25:44","date_gmt":"2020-07-16T10:25:44","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=3892"},"modified":"2026-03-18T14:52:02","modified_gmt":"2026-03-18T12:52:02","slug":"inside-criville-angel-nieto-el-primer-campeon-espanol","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/","title":{"rendered":"Inside \u00c1lex Crivill\u00e9:  \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol"},"content":{"rendered":"<p>Tras la dedicada al pentacampe\u00f3n del mundo\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/alex-criville-mick-doohan-historia-de-una-rivalidad\/\">Mick Doohan<\/a>, la serie de documentales\u00a0<em>Inside \u00c1lex Crivill\u00e9<\/em>\u00a0ya tiene una nueva entrega dedicada a otro piloto de leyenda:\u00a0<strong>\u00c1ngel Nieto<\/strong>. \u00cddolo, consejero y amigo, el recordado\u00a0<em>12+1<\/em>\u00a0tambi\u00e9n marc\u00f3 un antes y un despu\u00e9s en la vida del embajador AMV. \u201cSiempre he visto a\u00a0<strong>\u00c1ngel Nieto<\/strong> como a un h\u00e9roe\u201d, comenta \u00c1lex desde su Seva natal.<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/1tZkd4MmtGE?si=D289a9kjc-eQzbT6\" width=\"600\" height=\"415\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/uIWvV756yFs?si=npLsyzJl7vOmH2Mu\" width=\"600\" height=\"415\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 class=\"wp-block-heading\">\u00c1ngel Nieto:\u00a0<strong>\u00cddolo de la infancia junto a Ricardo Tormo<\/strong><\/h2>\n<p>Crivill\u00e9 vino al mundo el 4 de marzo de 1970. Por aquel entonces,\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0(Zamora, 1947) comenzaba a forjar su leyenda con t\u00edtulos nacionales y mundiales de motociclismo en las cilindradas m\u00e1s peque\u00f1as. Y continu\u00f3 engrosando su envidiable palmar\u00e9s mientras \u00c1lex crec\u00eda y comenzaba a picarle el gusanillo de las motos gracias a la afici\u00f3n de su hermano Josep. As\u00ed recuerda aquellos a\u00f1os:<\/p>\n<p><em>\u201cCuando era peque\u00f1o, mis \u00eddolos eran Ricardo Tormo, Freddie Spencer y Kenny Roberts. Pero \u00c1ngel era un piloto especial que hab\u00eda sumado muchos t\u00edtulos. Lo ten\u00eda en los p\u00f3steres de mi habitaci\u00f3n, era una pasada\u2026 \u00bfQui\u00e9n me iba a decir a m\u00ed que cuando \u00e9l se retirase yo pilotar\u00eda para la misma marca?\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Angel_Nieto_Un_piloto_muy_inteligente_y_picaro\" class=\"ez-toc-section\"><\/span>\u00c1ngel Nieto:\u00a0<strong>Un piloto muy inteligente y p\u00edcaro<\/strong><\/h2>\n<p>Gracias a\u00a0<strong>\u00c1ngel Nieto<\/strong>, el Mundial de Velocidad fue ganando adeptos en Espa\u00f1a. Y, poco a poco, el campeonato cobr\u00f3 un protagonismo cada vez mayor en la programaci\u00f3n de Televisi\u00f3n Espa\u00f1ola. Crivill\u00e9 reconoce que no vio muchas carreras del maestro por la peque\u00f1a pantalla. Pero, a pesar de ello, tiene claro que se trata de un aut\u00e9ntico superclase:<\/p>\n<p><em>\u201cNieto era superlisto y sab\u00eda manejar muy bien sus cartas. \u00a1Incluso en la parrilla era inteligente! En el\u00a0<\/em><a class=\"broken_link\" href=\"https:\/\/www.rtve.es\/alacarta\/videos\/motociclismo\/tdp-carreranieto-040817\/4148921\/\"><em>GP de Gran Breta\u00f1a de 1984<\/em><\/a><em>, \u00c1ngel se jugaba el t\u00edtulo de 125 cc y, como era costumbre en \u00e9l, dio unos peque\u00f1os golpes en el manillar de su moto para comprobar que todo estaba bien. Para su sorpresa, \u00a1se rompi\u00f3! Y como no hab\u00eda tiempo de cambiarlo, no se le ocurri\u00f3 otra cosa que tirar herramientas por el suelo. As\u00ed consigui\u00f3 retrasar la salida y pudieron reparar su Garelli\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Angel_Nieto_era_todo_un_estratega_encima_de_la_moto\" class=\"ez-toc-section\"><\/span>\u00c1ngel Nieto era t<strong>odo un estratega encima de la moto<\/strong><\/h2>\n<p>Quienes hayan visto competir a\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0recordar\u00e1n que era un gran estratega. Cuando marchaba por detr\u00e1s de sus rivales, el zamorano los estudiaba minuciosamente. Y si lideraba la carrera, sol\u00eda girarse a menudo para saber d\u00f3nde se encontraban y cu\u00e1l era su ventaja. Un estilo de pilotaje que no pas\u00f3 desapercibido para \u00c1lex Crivill\u00e9:<\/p>\n<p><em>\u201c\u00c1ngel era un piloto muy fino y h\u00e1bil. Sab\u00eda leer las carreras y ser conservador cuando era necesario. A sus rivales siempre los enga\u00f1aba y eleg\u00eda el mejor momento para adelantar. \u00a1Era el m\u00e1s listo de todos! Por eso consigui\u00f3 tantos t\u00edtulos mundiales\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Encuentro_con_el_maestro_en_Calafat\" class=\"ez-toc-section\"><\/span><strong>Encuentro con el maestro en Calafat<\/strong><\/h2>\n<p>Crivill\u00e9 inici\u00f3 su andadura como piloto en el Crit\u00e9rium de la revista\u00a0<em>Solo Moto<\/em>, que tambi\u00e9n organizaba el Superprestigio. En 1986,\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0particip\u00f3 en dicho trofeo para despedirse de la afici\u00f3n. Y fue all\u00ed, en el circuito de Calafat, donde \u00c1lex conoci\u00f3 a la leyenda del motociclismo espa\u00f1ol.<\/p>\n<p><em>\u201cConoc\u00ed a \u00c1ngel en Calafat. El corr\u00eda con Derbi y tuvo una ca\u00edda muy fea, un \u2018highside\u2019. Aquella fue su \u00faltima carrera. Un a\u00f1o despu\u00e9s, yo disput\u00e9 el Campeonato de Europa con Derbi y \u00e9l mont\u00f3 un gran equipo en 250 cc, patrocinado por Julio Iglesias, en el que estaba Alberto Puig. Pero conoc\u00ed realmente a Nieto como persona mucho m\u00e1s tarde, cuando trabajamos juntos en Televisi\u00f3n Espa\u00f1ola\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Una_referencia_para_los_pilotos_espanoles\" class=\"ez-toc-section\"><\/span><strong>Una referencia para los pilotos espa\u00f1oles<\/strong><\/h2>\n<p>Como bien recuerda \u00c1lex Crivill\u00e9,\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0continu\u00f3 ligado al Mundial de Velocidad despu\u00e9s de colgar el mono y el casco. Bien en un box, en el muro del\u00a0<em>pit lane<\/em>\u00a0o en su\u00a0<em>motorhome<\/em>, bien como comentarista de televisi\u00f3n, el\u00a0<em>12+1<\/em>\u00a0fue un habitual de los circuitos hasta su fallecimiento. Y siempre tuvo tiempo para hablar con todo el mundo, incluidos, c\u00f3mo no, los pilotos espa\u00f1oles:<\/p>\n<p><em>\u201cAcud\u00edamos a su \u2018motorhome\u2019 despu\u00e9s de los entrenamientos para lamentarnos si no hab\u00edamos conseguido un buen tiempo. Y \u00e9l siempre nos transmit\u00eda tranquilidad y nos daba alg\u00fan consejo. En ese aspecto, Nieto era muy positivo y para nosotros era un alivio poder contar con su experiencia\u201d.<\/em><\/p>\n<p><em>\u201cA m\u00ed sol\u00eda decirme que disfrutase de la vida y de las motos, que no las dejase nunca porque era un mundo maravilloso y que aprovechase las oportunidades que se me presentaban. \u00c1ngel disfrutaba mucho y no dejaba de ir a ninguna carrera. Sin duda, fue una persona admirable y un tipo que disfrutaba de la vida\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Gran_companero_en_Television_Espanola\" class=\"ez-toc-section\"><\/span><strong>Gran compa\u00f1ero en Televisi\u00f3n Espa\u00f1ola<\/strong><\/h2>\n<p>Al igual que le sucedi\u00f3 a\u00a0<strong>\u00c1ngel Nieto<\/strong>, a Crivill\u00e9 le lleg\u00f3 el momento de poner punto final a su trayectoria deportiva. Concretamente, \u00c1lex anunci\u00f3 su retirada en 2002. Y no tard\u00f3 en sumarse a su \u00eddolo como comentarista del Mundial de Velocidad en Televisi\u00f3n Espa\u00f1ola. Una experiencia en la que el\u00a0<em>12+1<\/em>\u00a0result\u00f3 ser una gran ayuda para el de Seva:<\/p>\n<p><em>\u201c\u00c1ngel ya era comentarista cuando yo gan\u00e9 el t\u00edtulo mundial de 500 cc en 1999. \u00a1Lo celebramos a lo grande con todos los periodistas! Y poco despu\u00e9s fuimos compa\u00f1eros en Televisi\u00f3n Espa\u00f1ola. Yo no ten\u00eda experiencia y me daba miedo decir alguna locura en el micr\u00f3fono. Pero Nieto siempre me aconsejaba y tranquilizaba. \u201cNo te preocupes, habla y d\u00e9jate llevar\u201d, me dec\u00eda\u201d.<\/em><\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Todo_pasion_y_corazon_asi_era_Angel_Nieto\" class=\"ez-toc-section\"><\/span><strong>Todo pasi\u00f3n y coraz\u00f3n: as\u00ed era \u00c1ngel Nieto<\/strong><\/h2>\n<p>El\u00a0<em>Inside \u00c1lex Crivill\u00e9<\/em>\u00a0dedicado a\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0va tocando a su fin. Echando la vista atr\u00e1s, nuestro embajador esboza una sonrisa al hablar de un caballero, alguien envidiable que sab\u00eda manejarse muy bien y con el que las risas siempre estaban garantizadas:<\/p>\n<p><em>\u201c\u00c1ngel era amigo de sus amigos. Y en las cenas no parabas de re\u00edrte con \u00e9l cuando contaba an\u00e9cdotas de sus carreras. Se le echa mucho en falta. Fue un tipo admirable que disfrutaba de la vida. Y que ten\u00eda el esp\u00edritu de un chaval. \u00a1Parec\u00eda que tuviese 20 a\u00f1os! La verdad es que te lo pasabas muy bien con \u00e9l\u201d.<\/em><\/p>\n<p><strong>\u00c1ngel Nieto<\/strong>\u00a0falleci\u00f3 el 3 de agosto de 2017 a los 70 a\u00f1os de edad como consecuencia de un accidente de tr\u00e1fico en su querida isla de Ibiza. Poco despu\u00e9s, se le rindi\u00f3 un multitudinario y emotivo homenaje en las calles de Madrid y en la que fue su casa: el circuito del Jarama, escenario de algunas de sus grandes gestas.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Palmares_de_Angel_Nieto_1964-1986\" class=\"ez-toc-section\"><\/span><strong>Palmar\u00e9s de \u00c1ngel Nieto (1964-1986)<\/strong><\/h2>\n<p>Nacido en Zamora pero criado en el madrile\u00f1o distrito de Vallecas,\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0situ\u00f3 a Espa\u00f1a en el mapa del motociclismo mundial gracias a sus\u00a0<em>12+1<\/em>\u00a0t\u00edtulos \u2013siempre evit\u00f3 referirse al considerado n\u00famero de la mala suerte\u2013. Y en el\u00a0<em>ranking<\/em>\u00a0de pilotos con m\u00e1s entorchados solamente es superado por su gran amigo Giacomo Agostini, que sum\u00f3 un total de 15 entre 1966 y 1975.<\/p>\n<p>Gracias a la pasi\u00f3n que les transmiti\u00f3, sus hijos Gelete y Pablo y su sobrino Fonsi contin\u00faan paseando el apellido Nieto por los circuitos de medio mundo, orgullosos del legado de un personaje \u00fanico e irrepetible.<\/p>\n<ul>\n<li>Debut en el Mundial: GP de Espa\u00f1a de 1964.<\/li>\n<li>Primera\u00a0<em>pole position<\/em>: GP de Austria de 1974.<\/li>\n<li>Primera vuelta r\u00e1pida en carrera: GP de Espa\u00f1a de 1968.<\/li>\n<li>Primer podio: GP de los Pa\u00edses Bajos de 1967.<\/li>\n<li>Primera vitoria: GP de Alemania del Este de 1969.<\/li>\n<li>Victorias: 90.<\/li>\n<li>Podios: 139.<\/li>\n<li><em>Pole positions<\/em>: 21.<\/li>\n<li>Vueltas r\u00e1pidas en carrera: 81.<\/li>\n<li>T\u00edtulos mundiales:\u00a0<em>12+1<\/em>\u00a0(6 de 50 cc y 7 de 125 cc).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>All\u00e1 por 1969,\u00a0<strong>\u00c1ngel Nieto<\/strong>\u00a0se convirti\u00f3 en el primer espa\u00f1ol en ganar un t\u00edtulo mundial de motociclismo. \u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.<\/p>\n","protected":false},"author":2,"featured_media":3896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[64,15,65,73],"class_list":["post-3892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-motor","tag-leyendas","tag-moto","tag-motociclismo","tag-pilotos"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20200716"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV<\/title>\n<meta name=\"description\" content=\"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-16T10:25:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T12:52:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"Inside \u00c1lex Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol\",\"datePublished\":\"2020-07-16T10:25:44+00:00\",\"dateModified\":\"2026-03-18T12:52:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/\"},\"wordCount\":1311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/inside-alex-crivillejpg-scaled-1.jpg\",\"keywords\":[\"Leyendas\",\"Moto\",\"Motociclismo\",\"Pilotos\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/\",\"name\":\"Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/inside-alex-crivillejpg-scaled-1.jpg\",\"datePublished\":\"2020-07-16T10:25:44+00:00\",\"dateModified\":\"2026-03-18T12:52:02+00:00\",\"description\":\"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/inside-alex-crivillejpg-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/inside-alex-crivillejpg-scaled-1.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Inside \u00c1lex Crivill\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/inside-criville-angel-nieto-el-primer-campeon-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inside \u00c1lex Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV","description":"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/","og_locale":"es_ES","og_type":"article","og_title":"Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV","og_description":"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/","og_site_name":"Blog AMV","article_published_time":"2020-07-16T10:25:44+00:00","article_modified_time":"2026-03-18T12:52:02+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"Inside \u00c1lex Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol","datePublished":"2020-07-16T10:25:44+00:00","dateModified":"2026-03-18T12:52:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/"},"wordCount":1311,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg","keywords":["Leyendas","Moto","Motociclismo","Pilotos"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/","name":"Inside Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg","datePublished":"2020-07-16T10:25:44+00:00","dateModified":"2026-03-18T12:52:02+00:00","description":"\u00c1lex Crivill\u00e9 relata c\u00f3mo fue su relaci\u00f3n con \u00c1ngel Nieto, un aut\u00e9ntico piloto de leyenda, \u201cun tipo listo y divertido que ten\u00eda el esp\u00edritu de un chaval\u201d.","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2020\/07\/inside-alex-crivillejpg-scaled-1.jpg","width":1200,"height":675,"caption":"Inside \u00c1lex Crivill\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/inside-criville-angel-nieto-el-primer-campeon-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"Inside \u00c1lex Crivill\u00e9: \u00c1ngel Nieto, el primer campe\u00f3n espa\u00f1ol"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=3892"}],"version-history":[{"count":1,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3892\/revisions"}],"predecessor-version":[{"id":7015,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3892\/revisions\/7015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/3896"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=3892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=3892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=3892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}