{"id":3958,"date":"2020-05-07T10:45:48","date_gmt":"2020-05-07T08:45:48","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=3958"},"modified":"2024-11-18T10:48:16","modified_gmt":"2024-11-18T08:48:16","slug":"fases-de-desescalada-cuando-podre-montar-en-moto","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/","title":{"rendered":"\u00bfCu\u00e1ndo puedo montar en moto en la fase de desescalada?"},"content":{"rendered":"<p>El 14 de marzo, con la publicaci\u00f3n del\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/14\/pdfs\/BOE-A-2020-3692.pdf\">Real Decreto 463\/2020<\/a>, se declaraba el estado de alarma en Espa\u00f1a con el objetivo de gestionar la situaci\u00f3n de crisis sanitaria provocada por el COVID-19. Y el pasado 28 de abril se aprobaba el\u00a0<a class=\"broken_link\" href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/sanidad14\/Documents\/2020\/03052020_Desescalada.pdf\"><em>Plan para la transici\u00f3n hacia una nueva normalidad<\/em><\/a>. Un documento que ha motivado que muchos motoristas se pregunten cu\u00e1ndo podr\u00e1n\u00a0<strong>montar en moto en fase de desescalada<\/strong>.<\/p>\n<p>En ese camino hacia la nueva normalidad se han establecido cuatro fases de desescalada. Y se prev\u00e9 que la duraci\u00f3n m\u00ednima de cada una de ellas sea de dos semanas. Un proceso, pues, que deber\u00eda concluir a finales de junio con la Fase III, en la que se contemplan desde protocolos de reincorporaci\u00f3n presencial a las empresas para la actividad laboral hasta la apertura de playas en condiciones de seguridad y distanciamiento.<\/p>\n<p>Si quieres saber cu\u00e1ndo podr\u00e1s\u00a0<strong>montar en moto en fase de desescalada<\/strong>, nos ocupamos de las novedades de la Fase 0 y de las que llegar\u00e1n con las fases I, II y III. \u00a1Toma nota!<\/p>\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 actividades est\u00e1n incluidas en el Real Decreto 463\/2020?<\/strong><\/h2>\n<p>Con excepci\u00f3n de las islas de Formentera, la Gomera, el Hierro y la Graciosa \u2013que han pasado directamente a la Fase I\u2013, la mayor\u00eda del territorio espa\u00f1ol se encuentra en la Fase 0 o de preparaci\u00f3n de la desescalada. Mientras dure la misma, los ciudadanos podr\u00e1n circular por las v\u00edas de uso p\u00fablico para realizar alguna de las actividades contempladas en el Real Decreto 463\/2020:<\/p>\n<ul>\n<li>Adquirir alimentos, productos farmac\u00e9uticos y art\u00edculos de primera necesidad.<\/li>\n<li>Acudir a centros, servicios y establecimientos sanitarios.<\/li>\n<li>Desplazarse al lugar de trabajo para efectuar una prestaci\u00f3n laboral, profesional o empresarial.<\/li>\n<li>Regresar al lugar de residencia habitual.<\/li>\n<li>Asistir y cuidar a mayores, menores, dependientes, personas con discapacidad o ciudadanos especialmente vulnerables.<\/li>\n<li>Desplazarse a entidades financieras y de seguros.<\/li>\n<li>Desplazarse por causa de fuerza mayor o situaci\u00f3n de necesidad.<\/li>\n<li>Llevar a cabo cualquier otra actividad de an\u00e1loga naturaleza que habr\u00e1 de hacerse individualmente, salvo que se acompa\u00f1e a personas con discapacidad o por otra causa justificada.<\/li>\n<\/ul>\n<p>En el caso de los veh\u00edculos particulares, pueden usarse siempre y cuando los desplazamientos est\u00e9n relacionados con una de las actividades referidas o para el repostaje en gasolineras o estaciones de servicio.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"%C2%BFQue_desplazamientos_en_moto_se_pueden_hacer_en_la_Fase_0\" class=\"ez-toc-section\"><\/span><strong>\u00bfQu\u00e9 desplazamientos en moto se pueden hacer en la Fase 0?<\/strong><\/h2>\n<p>En vigor desde el 4 de mayo, la Fase 0 introduce algunos cambios en lo relativo a la movilidad fuera del domicilio y medidas con un riesgo asociado de contagio muy bajo o nulo. Siempre, eso s\u00ed, que se cumplan las indicaciones de seguridad recomendadas por las autoridades sanitarias.<\/p>\n<p>Como novedad, en la Fase 0 se permite la apertura de peque\u00f1os negocios como peluquer\u00edas, ferreter\u00edas o centros de fisioterapia. Y podremos acudir a ellos siempre que hayamos solicitado cita previa. Pero, \u00bfpodemos\u00a0<strong>montar en moto en esta fase de desescalada<\/strong>\u00a0para ir a cortarnos el pelo o comprar una herramienta?<\/p>\n<p>Sobre esta cuesti\u00f3n en particular, y ante las dudas que suscita la Fase 0 entre los conductores, desde el\u00a0<a href=\"\"><strong>blog de AMV<\/strong><\/a>\u00a0nos hemos puesto en contacto con las Fuerzas y Cuerpos de Seguridad y la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.ocu.org\/\">Organizaci\u00f3n de Consumidores y Usuarios (OCU)<\/a>. Y podemos concluir que:<\/p>\n<ul>\n<li>En la Fase 0 podremos utilizar nuestra moto para desplazarnos a un establecimiento que se encuentre en nuestro municipio y en el que hayamos solicitado cita previa con antelaci\u00f3n.<\/li>\n<li>Para evitar ser sancionados en un control de tr\u00e1fico, es importante que conservemos un justificante de cita previa.<\/li>\n<li>A tenor de lo establecido en la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/eli\/es\/o\/2020\/05\/03\/snd388\/dof\/spa\/pdf\">Orden SND\/388\/2020<\/a>\u00a0del Ministerio de Sanidad, Consumo y Bienestar Social, solamente podremos salir de nuestro municipio, de manera excepcional, si el servicio o producto que deseamos no se encuentra disponible en el mismo.<\/li>\n<li>En cualquier caso, debe imperar el sentido com\u00fan y evitar recorrer muchos kil\u00f3metros. Conviene recordar que no est\u00e1n permitidos los desplazamientos interprovinciales y que persiste el riesgo de contagio.<\/li>\n<\/ul>\n<p>As\u00ed pues, podemos\u00a0<strong>montar en moto en fase de desescalada<\/strong>\u00a0en las actividades contempladas en el Real Decreto 463\/2020. Y en la Fase 0 tambi\u00e9n, por ejemplo, para acudir a un peque\u00f1o establecimiento con cita previa o un huerto familiar de autoconsumo dentro de nuestro municipio. \u00a1Y siempre poniendo en pr\u00e1ctica las medidas de higiene y seguridad recomendadas!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"%C2%BFPuede_utilizarse_la_moto_para_ir_a_hacer_deporte\" class=\"ez-toc-section\"><\/span><strong>\u00bfPuede utilizarse la moto para ir a hacer deporte?<\/strong><\/h2>\n<p>Por cierto, en la Fase 0 ya puedes practicar deporte en distintas franjas horarias. Pero debes saber que la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/01\/pdfs\/BOE-A-2020-4767.pdf\">Orden SND\/380\/2020<\/a>\u00a0establece lo siguiente:<\/p>\n<ul>\n<li>No se puede hacer uso de un veh\u00edculo motorizado o de transporte p\u00fablico para desplazarse a v\u00edas o espacios de uso p\u00fablico con el fin de practicar la actividad f\u00edsica prevista en dicha orden (pr\u00e1ctica no profesional de cualquier deporte individual).<\/li>\n<\/ul>\n<p>Por lo tanto, de momento no podr\u00e1s\u00a0<strong>montar en moto en fase de desescalada<\/strong>\u00a0para desplazarte a un lugar donde vayas a realizar una actividad f\u00edsica no profesional. Para la pr\u00e1ctica de actividades deportivas relacionadas con el mundo de la moto (por ejemplo, tandas en circuito), te aconsejamos ponerte en contacto con la\u00a0<a class=\"broken_link\" href=\"http:\/\/www.rfme.com\/web\">Real Federaci\u00f3n Motociclista Espa\u00f1ola (RFME)<\/a>\u00a0o las federaciones territoriales.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Dos_personas_en_moto_%C2%BFque_dice_la_orden_ministerial\" class=\"ez-toc-section\"><\/span><strong>Dos personas en moto: \u00bfqu\u00e9 dice la orden ministerial?<\/strong><\/h2>\n<p>Respecto a si dos personas pueden\u00a0<strong>montar en moto en fase de desescalada<\/strong>, es otro de los temas que est\u00e1 generando dudas entre los motoristas. Sobre todo, a ra\u00edz de la publicaci\u00f3n de la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/03\/pdfs\/BOE-A-2020-4789.pdf\">Orden TMA\/384\/2020<\/a>\u00a0del Ministerio de Transportes, Movilidad y Agenda Urbana. Sobre la ocupaci\u00f3n de los veh\u00edculos, la orden observa que:<\/p>\n<ul>\n<li>En los transportes privados particulares y privados complementarios de personas en veh\u00edculos de hasta nueve plazas, incluido el conductor, podr\u00e1n desplazarse dos personas por cada fila de asientos, siempre que utilicen mascarillas y respeten la m\u00e1xima distancia posible entre los ocupantes.<\/li>\n<li>En los veh\u00edculos en los que, por sus caracter\u00edsticas t\u00e9cnicas, \u00fanicamente se disponga de una fila de asientos, como en el supuesto de cabinas de veh\u00edculos pesados, furgonetas u otros, podr\u00e1n viajar como m\u00e1ximo dos personas, siempre que sus ocupantes utilicen mascarillas que cubran las v\u00edas respiratorias y guarden la m\u00e1xima distancia posible. En caso contrario, \u00fanicamente podr\u00e1 viajar el conductor.<\/li>\n<\/ul>\n<p>Por lo expuesto, y teniendo en cuenta que en una moto no se puede guardar la misma distancia de seguridad que en un coche, lo aconsejable, hasta la publicaci\u00f3n de normas m\u00e1s permisivas, es que solamente viaje una persona en la moto.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Evolucion_de_la_desescalada_fases_I_II_y_III\" class=\"ez-toc-section\"><\/span><strong>Evoluci\u00f3n de la desescalada: fases I, II y III<\/strong><\/h2>\n<p>Tras la fase 0 llegar\u00e1n otras tres que dar\u00e1n paso a la nueva normalidad. Etapas en las que, de forma progresiva, podremos participar en peque\u00f1as reuniones sociales, tomar una consumici\u00f3n en una terraza, viajar a segundas residencias dentro de nuestra provincia, acudir a espect\u00e1culos culturales, etc.<\/p>\n<p>Sobre los detalles de\u00a0<strong>montar en moto en esas fases de desescalada<\/strong>, desde las Fuerzas y Cuerpos de Seguridad nos invitan a conservar la paciencia. Seg\u00fan se vayan anunciando, tendremos m\u00e1s claro cu\u00e1les son las particularidades de cada fase en materia de movilidad. \u00a1Ya falta menos para la nueva normalidad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de semanas de confinamiento, cada vez son m\u00e1s los motoristas que se preparan para\u00a0<strong>montar en moto en fase de desescalada<\/strong>. Pero tendr\u00e1n que hacerlo poco a poco\u2026 \u00a1Ya falta menos para disfrutar de la nueva normalidad!<\/p>\n","protected":false},"author":2,"featured_media":3959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[15],"class_list":["post-3958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-motor","tag-moto"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20200507"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV<\/title>\n<meta name=\"description\" content=\"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-07T08:45:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T08:48:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"\u00bfCu\u00e1ndo puedo montar en moto en la fase de desescalada?\",\"datePublished\":\"2020-05-07T08:45:48+00:00\",\"dateModified\":\"2024-11-18T08:48:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/\"},\"wordCount\":1227,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/montar-en-moto-en-fase-desescalada-1.jpeg\",\"keywords\":[\"Moto\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/\",\"name\":\"Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/montar-en-moto-en-fase-desescalada-1.jpeg\",\"datePublished\":\"2020-05-07T08:45:48+00:00\",\"dateModified\":\"2024-11-18T08:48:16+00:00\",\"description\":\"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/montar-en-moto-en-fase-desescalada-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/montar-en-moto-en-fase-desescalada-1.jpeg\",\"width\":850,\"height\":567,\"caption\":\"Cuando volver a montar en moto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/fases-de-desescalada-cuando-podre-montar-en-moto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfCu\u00e1ndo puedo montar en moto en la fase de desescalada?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV","description":"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/","og_locale":"es_ES","og_type":"article","og_title":"Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV","og_description":"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/","og_site_name":"Blog AMV","article_published_time":"2020-05-07T08:45:48+00:00","article_modified_time":"2024-11-18T08:48:16+00:00","og_image":[{"width":850,"height":567,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"\u00bfCu\u00e1ndo puedo montar en moto en la fase de desescalada?","datePublished":"2020-05-07T08:45:48+00:00","dateModified":"2024-11-18T08:48:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/"},"wordCount":1227,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg","keywords":["Moto"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/","name":"Fases de desescalada, \u00bfcu\u00e1ndo podr\u00e9 montar en moto? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg","datePublished":"2020-05-07T08:45:48+00:00","dateModified":"2024-11-18T08:48:16+00:00","description":"Despu\u00e9s de semanas de confinamiento, los motoristas que se preparan para montar en moto en fase de desescalada. \u00bfQuieres saber c\u00f3mo puedes hacerlo? + info:","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/montar-en-moto-en-fase-desescalada-1.jpeg","width":850,"height":567,"caption":"Cuando volver a montar en moto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/fases-de-desescalada-cuando-podre-montar-en-moto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"\u00bfCu\u00e1ndo puedo montar en moto en la fase de desescalada?"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=3958"}],"version-history":[{"count":0,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/3959"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=3958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=3958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=3958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}