{"id":3969,"date":"2020-05-19T10:56:02","date_gmt":"2020-05-19T08:56:02","guid":{"rendered":"https:\/\/dev.jorgesimon.es\/?p=3969"},"modified":"2026-03-18T16:53:48","modified_gmt":"2026-03-18T14:53:48","slug":"10-razones-para-usar-la-moto-durante-el-coronavirus","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/","title":{"rendered":"Razones para usar la Moto durante el Coronavirus"},"content":{"rendered":"<p>Nos encaminamos hacia una \u201cnueva normalidad\u201d que, hasta la aparici\u00f3n de medicamentos o vacunas espec\u00edficos contra el coronavirus, condicionar\u00e1 nuestros h\u00e1bitos. En lo relativo a la movilidad, \u00bfsab\u00edas que los ministerios de Sanidad, Consumo y Bienestar Social y de Transportes, Movilidad y Agenda Urbana han recomendado\u00a0<strong>usar la moto<\/strong>?<\/p>\n<p>Concretamente, ambos ministerios han aconsejado el uso de veh\u00edculos privados de cara a evitar aglomeraciones en el transporte p\u00fablico. Pero, como veremos a continuaci\u00f3n, existen, al menos, otras nueve razones m\u00e1s para\u00a0<strong>usar la moto<\/strong>\u00a0tanto en las distintas fases de desescalada como en la \u201cnueva normalidad\u201d. \u00a1Toma nota!<\/p>\n<h2 class=\"wp-block-heading\"><strong>Alternativa segura al transporte p\u00fablico<\/strong><\/h2>\n<p>Frente al COVID-19, el confinamiento produce una sensaci\u00f3n de seguridad. Pero, \u00bfqu\u00e9 sucede si tenemos que salir de nuestro domicilio? En el caso del transporte p\u00fablico, el uso de mascarilla es obligatorio. Sin embargo, es probable que algunos ciudadanos sientan temor ante la posibilidad de que no se cumpla el distanciamiento social.<\/p>\n<p>Para nuestros desplazamientos diarios,\u00a0<strong>usar la moto<\/strong>\u00a0es una magn\u00edfica opci\u00f3n. Por lo general, en las motos suele viajar una persona. As\u00ed pues, ayudan a evitar el contacto con otros ciudadanos. Y, por lo tanto, reducen la exposici\u00f3n al COVID-19.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"La_moto_contribuye_a_descongestionar_el_trafico\" class=\"ez-toc-section\"><\/span><strong>La moto contribuye a descongestionar el tr\u00e1fico<\/strong><\/h2>\n<p>Durante el confinamiento, el volumen de tr\u00e1fico ha disminuido notablemente en las principales ciudades de nuestro pa\u00eds. Sin embargo, con el objetivo de prevenir contagios, es previsible que cada vez sean m\u00e1s los conductores que decidan hacer uso del veh\u00edculo privado.<\/p>\n<p>Entre otras ventajas, desde la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.anesdor.com\/\">Asociaci\u00f3n Nacional de Empresas del Sector de Dos Ruedas (Anesdor)<\/a>\u00a0recuerdan que las motos contribuyen a descongestionar el tr\u00e1fico. Si se reemplazara el 10% de los veh\u00edculos por motos, los atascos se reducir\u00edan un 40%. \u00a1Otra buena raz\u00f3n para\u00a0<strong>usar la moto<\/strong>!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Vehiculo_respetuoso_con_el_medio_ambiente\" class=\"ez-toc-section\"><\/span><strong>Veh\u00edculo respetuoso con el medio ambiente<\/strong><\/h2>\n<p>L\u00f3gicamente, la reducci\u00f3n del tr\u00e1fico ha conllevado un descenso significativo de las emisiones contaminantes. Pero, \u00bfqu\u00e9 suceder\u00e1 cuando vuelva a hacerse un uso masivo del veh\u00edculo privado? \u00bfNuestras ciudades volver\u00e1n a estar cubiertas por una nube de contaminaci\u00f3n?<\/p>\n<p>Si deseamos que no sea as\u00ed,\u00a0<strong>usar la moto<\/strong>\u00a0ayuda a reducir las emisiones. Comparadas con otros veh\u00edculos, las motos generan menos emisiones de di\u00f3xido de carbono (CO<sub>2<\/sub>) y de di\u00f3xido de nitr\u00f3geno (NO<sub>2<\/sub>) y part\u00edculas en suspensi\u00f3n. Ello es as\u00ed gracias al esfuerzo de los fabricantes y la aplicaci\u00f3n de normas como la Euro 4 y la\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/normativa-euro-5-que-es-y-como-nos-afecta\/\">Euro 5<\/a>.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Menor_tiempo_en_los_desplazamientos_urbanos\" class=\"ez-toc-section\"><\/span><strong>Menor tiempo en los desplazamientos urbanos<\/strong><\/h2>\n<p>Desde Anesdor tambi\u00e9n recuerdan que, en comparaci\u00f3n con otros veh\u00edculos, las motos reducen el tiempo de los recorridos urbanos entre un 50% y un 70%. Y no es la \u00fanica entidad que hace hincapi\u00e9 en ello. Hace unos a\u00f1os, la\u00a0<a class=\"broken_link\" href=\"https:\/\/www.femamotorcycling.eu\/\">Federaci\u00f3n Europea de Asociaciones de Motoristas<\/a>\u00a0public\u00f3 un estudio que pon\u00eda de manifiesto la rapidez de la moto en varias ciudades del Viejo Continente.<\/p>\n<p>En el caso de Oslo, por poner un ejemplo, mientras un automovilista invert\u00eda 65 minutos en recorrer 29 kil\u00f3metros entre un barrio perif\u00e9rico y el centro de la ciudad, un motorista realizaba el trayecto en 27 minutos. Concluyente, \u00bfverdad?<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Autonomia_garantizada_%C2%A1Una_preocupacion_menos\" class=\"ez-toc-section\"><\/span><strong>Autonom\u00eda garantizada. \u00a1Una preocupaci\u00f3n menos!<\/strong><\/h2>\n<p>Otra de las razones para\u00a0<strong>usar la moto<\/strong>\u00a0en ciudad es que ofrece un rango de distancia amplio. Como explicamos en el post\u00a0<a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/cuanto-cuesta-mantener-una-moto-de-125-cc\/\"><em>\u00bfCu\u00e1nto te cuesta mantener una moto de 125 cc?<\/em><\/a>, la autonom\u00eda de algunos modelos de 125 cc, aut\u00e9nticos superventas del mercado espa\u00f1ol, es superior a 450 kil\u00f3metros.<\/p>\n<p>Y si optamos por movernos en motos el\u00e9ctricas, debes saber que una de sus ventajas es la autonom\u00eda. S\u00ed, \u00a1has o\u00eddo bien! Hoy en d\u00eda, las bater\u00edas extra\u00edbles pueden recargarse en un enchufe convencional mientras dormimos, trabajamos o estudiamos. As\u00ed, \u00a1siempre tendr\u00e1s el\u00a0<em>dep\u00f3sito<\/em>\u00a0lleno!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Practicidad_%C2%A1media_casa_a_cuestas\" class=\"ez-toc-section\"><\/span><strong>Practicidad: \u00a1media casa a cuestas!<\/strong><\/h2>\n<p>Entre las razones que invitan a\u00a0<strong>usar la moto<\/strong>\u00a0en las fases de desescalada y la \u201cnueva normalidad\u201d se encuentra su practicidad. S\u00ed, es cierto: una moto no tiene el maletero de una berlina o el volumen de carga de un\u00a0<em>station wagon<\/em>. \u00a1Pero ello no significa que no podamos transportar nuestras pertenencias!<\/p>\n<p>Ya sea de serie o como opci\u00f3n, tenemos la posibilidad de disfrutar de ba\u00fales traseros, maletas o alforjas laterales, bolsas sobredep\u00f3sito\u2026 Y si vamos a desplazarnos en un\u00a0<em>scooter<\/em>, contaremos con guanteras y un cofre bajo el asiento donde podremos guardar nuestro casco. \u00bfQui\u00e9n dijo que las motos no eran pr\u00e1cticas?<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Facilidad_de_aparcamiento_en_ciudad\" class=\"ez-toc-section\"><\/span><strong>Facilidad de aparcamiento en ciudad<\/strong><\/h2>\n<p>La \u201cnueva normalidad\u201d traer\u00e1 consigo problemas de aparcamiento. Por ello, los grandes municipios deber\u00edan fomentar el uso de la moto. Llegado el momento de aparcar, las motos ocupan cinco veces menos espacio que otros veh\u00edculos. \u00a1Conviene tenerlo en cuenta!<\/p>\n<p>Si vas a\u00a0<strong>usar la moto<\/strong>, procura aparcarla en espacios habilitados para tal fin, en zonas de estacionamiento regulado o en la calzada junto a la acera. En esta \u00faltima tambi\u00e9n podr\u00e1s aparcar siempre que respetes la normativa municipal y no obstaculices el paso de peatones u otros veh\u00edculos. \u00a1No lo olvides!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Precio_de_adquisicion_%C2%A1ahorro_garantizado\" class=\"ez-toc-section\"><\/span><strong>Precio de adquisici\u00f3n: \u00a1ahorro garantizado!<\/strong><\/h2>\n<p>Continuando con las razones que aconsejan\u00a0<strong>usar la moto<\/strong>\u00a0en estos tiempos, su precio es inferior al de un autom\u00f3vil. Por ello, si estabas pensando en comprar una moto antes de que se decretase el estado de alarma y el confinamiento, \u00a1no lo dudes!<\/p>\n<p>Inf\u00f3rmate en los puntos de venta. En ellos encontrar\u00e1s ofertas, promociones y planes de financiaci\u00f3n que te ayudar\u00e1n a estrenar compa\u00f1era de aventuras. Si te decantas por una moto el\u00e9ctrica, pregunta en el concesionario si puedes beneficiarte de ayudas p\u00fablicas a la adquisici\u00f3n.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Menor_gasto_en_el_mantenimiento_y_el_seguro\" class=\"ez-toc-section\"><\/span><strong>Menor gasto en el mantenimiento y el seguro<\/strong><\/h2>\n<p>Asimismo, una moto requiere un menor desembolso econ\u00f3mico en concepto de puesta a punto. Por cierto, si tu compa\u00f1era de aventuras ha estado parada durante el confinamiento, te animamos a leer el post\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/mantenimiento-de-la-moto-factor-clave-de-la-seguridad\/\"><em>Consejos de mantenimiento para moto despu\u00e9s de la cuarentena<\/em><\/a>. As\u00ed podr\u00e1s volver a circular con mayor seguridad.<\/p>\n<p>Y si tienes que asegurar tu moto, tambi\u00e9n te ahorrar\u00e1s un dinero en comparaci\u00f3n con un autom\u00f3vil. En\u00a0<a class=\"broken_link\" href=\"https:\/\/www.amv.es\/\"><strong>AMV<\/strong><\/a>\u00a0somos especialistas en seguros de moto y te lo ponemos f\u00e1cil a la hora de asegurar una motocicleta, un\u00a0<em>scooter<\/em>\u00a0o una moto cl\u00e1sica. \u00a1Podr\u00e1s personalizar tu p\u00f3liza con las coberturas que realmente necesites!<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"Compatibilidad_con_el_carnet_B_de_coche\" class=\"ez-toc-section\"><\/span><strong>Compatibilidad con el carnet B de coche<\/strong><\/h2>\n<p>Por \u00faltimo, es muy importante destacar que\u00a0<a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-motos-se-pueden-conducir-con-el-carnet-de-coche\/\">los titulares del carnet B de coche pueden conducir algunas motos<\/a>. Para los automovilistas, es otra de las razones que les anima a\u00a0<strong>usar la moto<\/strong>. Sobre todo los\u00a0<em>scooters<\/em>, ya que, al equipar una transmisi\u00f3n de variador continuo, no obligan a accionar la maneta del embrague ni la palanca del cambio.<\/p>\n<p>Si te animas a dar el salto al mundo de la moto, te recomendamos que, antes de hacerlo, participes en un curso de conducci\u00f3n segura. En una jornada de formaci\u00f3n aprender\u00e1s a equiparte. Y tambi\u00e9n te ense\u00f1ar\u00e1n a adoptar una posici\u00f3n correcta sobre el veh\u00edculo, girar en zonas con poco espacio de maniobrabilidad, hacer un uso efectivo de los sistemas ABS y CBS, etc.<\/p>\n<h2 class=\"wp-block-heading\"><span id=\"10_razones_para_usar_la_moto_en_la_%E2%80%9Cnueva_normalidad%E2%80%9D\" class=\"ez-toc-section\"><\/span><strong>10 razones para usar la moto en la \u201cnueva normalidad\u201d<\/strong><\/h2>\n<p>Por todo lo expuesto, y a modo de resumen, estas son las principales razones que aconsejan\u00a0<strong>usar la moto<\/strong>\u00a0en las fases de desescalada y la \u201cnueva normalidad\u201d:<\/p>\n<ol type=\"1\">\n<li>Si se utiliza individualmente, la moto garantiza el distanciamiento social y es una magn\u00edfica alternativa al transporte p\u00fablico.<\/li>\n<li>Al ser un veh\u00edculo de dimensiones reducidas, la moto contribuye a eliminar los atascos. Un mayor n\u00famero de motos en la calle se traduce en una importante descongesti\u00f3n del tr\u00e1fico.<\/li>\n<li>Ahora que se ha reducido la contaminaci\u00f3n en las grandes ciudades, es importante apostar por veh\u00edculos m\u00e1s eficientes. Por sus bajas emisiones, la moto es protagonista de la movilidad sostenible.<\/li>\n<li>La moto invierte menos tiempo que otros veh\u00edculos en completar recorridos urbanos.<\/li>\n<li>Independientemente de si usamos un modelo de gasolina o el\u00e9ctrico, las motos actuales brindan una autonom\u00eda suficiente para los desplazamientos diarios.<\/li>\n<li>La capacidad de carga no puede ser excusa para no\u00a0<strong>usar la moto<\/strong>. Accesorios, guanteras o espacios bajo el asiento nos lo ponen f\u00e1cil para guardar el casco o transportar nuestro ordenador port\u00e1til.<\/li>\n<li>En comparaci\u00f3n con un autom\u00f3vil, una moto es m\u00e1s f\u00e1cil de aparcar en ciudad gracias a las distintas opciones existentes para tal fin.<\/li>\n<li>El precio de una moto es inferior al de un coche. Y las marcas y los concesionarios activan campa\u00f1as y ofertas para facilitar su compra.<\/li>\n<li>Una moto requiere menos gasto que un autom\u00f3vil en concepto de mantenimiento y seguro obligatorio.<\/li>\n<li>Finalmente, el carnet B de coche permite conducir algunas motos. Algo que aprovechan los automovilistas para ahorrar tiempo y dinero en sus desplazamientos.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Desde su condici\u00f3n de medio de transporte libre de contagios hasta la posibilidad de ser conducida por los titulares del carnet B de coche, existen muchas razones para\u00a0<strong>usar la moto<\/strong>\u00a0en las fases de desescalada y la \u201cnueva normalidad\u201d. \u00a1Las repasamos!<\/p>\n","protected":false},"author":2,"featured_media":3970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[15],"class_list":["post-3969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-motor","tag-moto"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":"20200518"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 razones para usar la Moto durante el Coronavirus | Blog AMV<\/title>\n<meta name=\"description\" content=\"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 razones para usar la Moto durante el Coronavirus | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T08:56:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T14:53:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"Razones para usar la Moto durante el Coronavirus\",\"datePublished\":\"2020-05-19T08:56:02+00:00\",\"dateModified\":\"2026-03-18T14:53:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/\"},\"wordCount\":1527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/usar-la-moto-1.jpeg\",\"keywords\":[\"Moto\"],\"articleSection\":[\"Noticias motor\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/\",\"name\":\"10 razones para usar la Moto durante el Coronavirus | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/usar-la-moto-1.jpeg\",\"datePublished\":\"2020-05-19T08:56:02+00:00\",\"dateModified\":\"2026-03-18T14:53:48+00:00\",\"description\":\"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/usar-la-moto-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/usar-la-moto-1.jpeg\",\"width\":850,\"height\":567,\"caption\":\"Razones para usar la moto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/10-razones-para-usar-la-moto-durante-el-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias motor\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/noticias-motor\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Razones para usar la Moto durante el Coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 razones para usar la Moto durante el Coronavirus | Blog AMV","description":"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"10 razones para usar la Moto durante el Coronavirus | Blog AMV","og_description":"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!","og_url":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/","og_site_name":"Blog AMV","article_published_time":"2020-05-19T08:56:02+00:00","article_modified_time":"2026-03-18T14:53:48+00:00","og_image":[{"width":850,"height":567,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"Razones para usar la Moto durante el Coronavirus","datePublished":"2020-05-19T08:56:02+00:00","dateModified":"2026-03-18T14:53:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/"},"wordCount":1527,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg","keywords":["Moto"],"articleSection":["Noticias motor"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/","url":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/","name":"10 razones para usar la Moto durante el Coronavirus | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg","datePublished":"2020-05-19T08:56:02+00:00","dateModified":"2026-03-18T14:53:48+00:00","description":"Existen muchas razones para usar la moto en las fases de desescalada y en la transici\u00f3n hacia la \u201cnueva normalidad\u201d tras el coronavirus.\u00a1Las repasamos aqu\u00ed!","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/usar-la-moto-1.jpeg","width":850,"height":567,"caption":"Razones para usar la moto"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/noticias-motor\/10-razones-para-usar-la-moto-durante-el-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Noticias motor","item":"https:\/\/www.amv.es\/blog\/noticias-motor\/"},{"@type":"ListItem","position":3,"name":"Razones para usar la Moto durante el Coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=3969"}],"version-history":[{"count":1,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3969\/revisions"}],"predecessor-version":[{"id":7039,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/3969\/revisions\/7039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/3970"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=3969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=3969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=3969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}