{"id":5425,"date":"2025-03-05T11:29:44","date_gmt":"2025-03-05T09:29:44","guid":{"rendered":"https:\/\/www.amv.es\/blog\/?p=5425"},"modified":"2026-02-12T14:43:42","modified_gmt":"2026-02-12T12:43:42","slug":"que-preguntar-al-comprar-moto-segunda-mano","status":"publish","type":"post","link":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/","title":{"rendered":"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?"},"content":{"rendered":"<h2>\u00bfQu\u00e9 preguntas aconsejamos hacer antes de comprar una moto de segunda mano?<\/h2>\n<p>Desde cu\u00e1ntos a\u00f1os y kil\u00f3metros tiene la moto hasta si pesa alguna multa o carga sobre ella, a la hora de <strong>comprar una moto de segunda mano<\/strong> es esencial que le plantees una serie de preguntas al vendedor. De esa forma, podr\u00e1s tomar una decisi\u00f3n informada y negociar el precio si adviertes que la moto necesita alguna reparaci\u00f3n o una puesta a punto.<\/p>\n<h3>1. \u00bfCu\u00e1ntos a\u00f1os y kil\u00f3metros tiene la moto?<\/h3>\n<p>En primer lugar, pregunta cu\u00e1ntos a\u00f1os y kilometraje tiene la moto. En este sentido, el hecho de que sea antigua y su od\u00f3metro refleje muchos kil\u00f3metros no debe asustarte. En lo referente a la <a href=\"https:\/\/www.amv.es\/blog\/https:\/\/www.amv.es\/blog\/noticias-motor\/cuantos-kilometros-de-vida-tiene-una-moto\/\">vida \u00fatil de una moto<\/a>, te sorprender\u00e1 saber que, con un mantenimiento adecuado, \u00a1algunas motos superan los 300.000 km!<\/p>\n<p>En este apartado, si bien no es sencillo comprobar si un <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/cuentakilometros-de-moto-tipos-y-caracteristicas\/\">cuentakil\u00f3metros de moto<\/a> ha sido manipulado, poner en pr\u00e1ctica estos consejos te ser\u00e1 de ayuda para intuir si el kilometraje es real:<\/p>\n<ul>\n<li aria-level=\"1\">Compara el kilometraje con el estado general de la moto. Si el od\u00f3metro marca pocos kil\u00f3metros, los pu\u00f1os, las estriberas, el asiento o los discos de freno no deber\u00edan presentar un desgaste excesivo.<\/li>\n<li aria-level=\"1\">Revisa el historial de la moto. Si solicitas un <a href=\"https:\/\/sede.dgt.gob.es\/es\/vehiculos\/informacion-de-vehiculos\/informe-de-un-vehiculo\/\">informe completo<\/a> de la moto en la Direcci\u00f3n General de Tr\u00e1fico (DGT), podr\u00e1s conocer el kilometraje y el historial de la Inspecci\u00f3n T\u00e9cnica de Veh\u00edculos (ITV) que consta en Tr\u00e1fico.<\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\">Comprueba los registros de mantenimiento. El vendedor tiene que facilitarte el libro en el que consten los trabajos de mantenimiento realizados en la moto. Y en ellos deber\u00eda figurar el kilometraje.<\/li>\n<\/ul>\n<h3>2. \u00bfCu\u00e1ntos due\u00f1os ha tenido?<\/h3>\n<p>Del mismo modo, si vas a <strong>comprar una moto de segunda mano<\/strong> tienes que preguntar cu\u00e1ntos due\u00f1os ha tenido, ya que conocer el n\u00famero de propietarios anteriores puede darte algunas pistas sobre la moto que deseas adquirir:<\/p>\n<ul>\n<li aria-level=\"1\">Si ha tenido varios due\u00f1os, eso podr\u00eda significar que la moto da problemas y sus propietarios no han quedado satisfechos con ella.<\/li>\n<li aria-level=\"1\">Sin embargo, una moto con un \u00fanico due\u00f1o y un buen historial de mantenimiento ser\u00e1, a priori, una mejor opci\u00f3n.<\/li>\n<\/ul>\n<p>A prop\u00f3sito: en el informe completo proporcionado por la DGT tambi\u00e9n figura el n\u00famero de titulares. Si vas a comprar una moto de ocasi\u00f3n, \u00a1no olvides solicitar dicho documento! Para obtenerlo, basta con conocer el n\u00famero de matr\u00edcula o bastidor de la moto y pagar una tasa de 8,67 euros.<\/p>\n<h3>3. \u00bfPara qu\u00e9 usaba la moto el \u00faltimo propietario?<\/h3>\n<p>Ya que nos hemos referido al propietario, preg\u00fantale al vendedor qu\u00e9 uso se le ha dado a la moto que est\u00e1 en venta:<\/p>\n<ul>\n<li aria-level=\"1\">\u00bfSe utilizaba a diario o de forma frecuente? \u00bfO solamente de forma ocasional?<\/li>\n<li aria-level=\"1\">\u00bfSe conduc\u00eda en ciudad? \u00bfO s\u00f3lo se usaba para desplazamientos interurbanos, rutas y <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/consejos-para-hacer-viajes-largos-en-moto\/\">viajes largos en moto<\/a>?<\/li>\n<li aria-level=\"1\">\u00bfY se aparcaba en la calle o se guardaba en un garaje comunitario o privado?<\/li>\n<\/ul>\n<p>Las respuestas a estas preguntas facilitar\u00e1n que te hagas una idea sobre el uso que se le ha dado a la moto y el desgaste de sus principales componentes.<\/p>\n<h3>4. \u00bfQu\u00e9 mantenimiento ha tenido la moto?<\/h3>\n<p>En ese sentido, al <strong>comprar una moto de segunda mano<\/strong> tambi\u00e9n es important\u00edsimo preguntar qu\u00e9 mantenimiento ha tenido. Y para saberlo, como ya se ha comentado, es de gran utilidad:<\/p>\n<ul>\n<li aria-level=\"1\">Consultar el informe completo de la moto proporcionado por la DGT, puesto que en \u00e9l se refleja el historial de ITV, el mantenimiento al que ha sido sometida y las llamadas a revisi\u00f3n pendientes.<\/li>\n<li aria-level=\"1\">De igual manera, el vendedor ha de proporcionar un libro o registro en el que figuren las labores de puesta a punto que se han hecho en la moto.<\/li>\n<\/ul>\n<p>Por cierto, si finalmente decides comprarla, en el blog te explicamos <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/mantenimiento-de-tu-moto-cada-cuanto-hacerlo\/\">cada cu\u00e1nto tiempo debes hacer el mantenimiento de la moto<\/a>. De esa forma, tu moto tendr\u00e1 una vida \u00fatil mayor y t\u00fa podr\u00e1s disfrutar de ella con seguridad sabiendo que se encuentra en perfecto estado de revista.<\/p>\n<h3>5. \u00bfEst\u00e1n todos los papeles en regla?<\/h3>\n<p>L\u00f3gicamente, si vas a <strong>comprar una moto de segunda mano<\/strong> es indispensable que le preguntes al vendedor si los <a href=\"https:\/\/www.amv.es\/blog\/noticias-motor\/papeles-y-documentacion-que-debes-llevar-en-tu-moto-para-no-ser-multado\/\">papeles de la moto<\/a> est\u00e1n en regla:<\/p>\n<ul>\n<li aria-level=\"1\">Permiso de circulaci\u00f3n. Este documento incluye los datos del titular e informaci\u00f3n de la moto: marca, modelo, cilindrada, matr\u00edcula, fecha de matriculaci\u00f3n, bastidor, etc.<\/li>\n<li aria-level=\"1\">Ficha t\u00e9cnica. Adem\u00e1s de incluir los principales datos t\u00e9cnicos de la moto, en la ficha constan todas las inspecciones (ITV) que ha pasado.<\/li>\n<\/ul>\n<p>Recuerda: si el permiso de circulaci\u00f3n no se encuentra en regla y la ITV no est\u00e1 en vigor, no se podr\u00e1 transferir la moto ni proceder al cambio de titularidad en la DGT. \u00a1No lo olvides!<\/p>\n<h3>6. \u00bfC\u00f3mo saber si una moto de segunda mano tiene multas o cargas?<\/h3>\n<p>Relacionado con el punto anterior, tambi\u00e9n es primordial preguntar si una moto de ocasi\u00f3n o de segunda mano tiene multas o cargas. Ello es as\u00ed porque su existencia puede dificultar la venta de la moto. Veamos\u2026<\/p>\n<ul>\n<li aria-level=\"1\">Multas. Si el propietario de la moto tiene alguna multa de tr\u00e1fico pendiente, p\u00eddele que la pague. De lo contrario, una multa impagada podr\u00eda dar lugar al embargo de la moto.<\/li>\n<li aria-level=\"1\">Embargos. Ya sea por multas pendientes, cualquier otra deuda, demandas o sentencias, si una moto est\u00e1 embargada no es recomendable adquirirla, ya que la DGT no permite transferir ni cambiar la titularidad de un veh\u00edculo hasta que se levante el embargo.<\/li>\n<li aria-level=\"1\">Reserva de dominio. Las motos que se han comprado mediante un cr\u00e9dito tienen un reserva de dominio. Eso significa que contin\u00faan siendo propiedad de la entidad financiera hasta que sus due\u00f1os salden la deuda. As\u00ed pues, no pueden venderse mientras la reserva no sea cancelada.<\/li>\n<li aria-level=\"1\">Precintos. Finalmente, si una moto ha sido precintada por orden de Hacienda, la Seguridad Social, la DGT, un juzgado, un ayuntamiento, etc., tampoco podr\u00e1 transferirse hasta que no se resuelva el problema que origin\u00f3 el precinto.<\/li>\n<\/ul>\n<p>Por su importancia, en el blog te explicamos c\u00f3mo <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/como-averiguar-si-tiene-multas-una-moto-de-segunda-mano\/\">averiguar si tiene multas una moto de segunda mano<\/a>. Y en el supuesto de que te surjan dudas sobre las sanciones y las cargas, no te compliques: acude a una gestor\u00eda especializada en la transferencia de veh\u00edculos para que sus profesionales te asesoren.<\/p>\n<h3>7. \u00bfPuedo probar la moto?<\/h3>\n<p>Y antes de tomar una decisi\u00f3n al <strong>comprar una moto de segunda mano<\/strong>, esta es una pregunta obvia que debes hacerle al vendedor: \u00ab\u00bfPuedo probar la moto?\u00bb. Recorrer unos kil\u00f3metros con ella te facilitar\u00e1 saber si se trata de tu media naranja. Durante esa toma de contacto:<\/p>\n<ul>\n<li aria-level=\"1\">Comprueba que te sientes c\u00f3modo sobre la moto y a sus mandos \u2013aprovecha para verificar que funcionan correctamente\u2013.<\/li>\n<li aria-level=\"1\">Observa la respuesta del motor y cerci\u00f3rate de que no presenta ruidos extra\u00f1os.<\/li>\n<li aria-level=\"1\">Y presta atenci\u00f3n tanto a la respuesta de las suspensiones y los frenos como del estado de los neum\u00e1ticos, pues conforman el denominado tri\u00e1ngulo de la <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-es-la-seguridad-vial-activa-y-pasiva\/\">seguridad activa<\/a>.<\/li>\n<\/ul>\n<p>En la adquisici\u00f3n de motos de segunda mano o de ocasi\u00f3n, una buena idea es consultar a un experto en mec\u00e1nica para que haga una valoraci\u00f3n general de la motocicleta y nos d\u00e9 su opini\u00f3n. \u00bfSe encuentra en buen estado? \u00bfVale el precio que piden por ella? \u00bfO conviene negociarlo porque la moto necesita alguna reparaci\u00f3n, sustituir componentes o ponerla a punto?<\/p>\n<p>Si necesitas m\u00e1s informaci\u00f3n al respecto, en el blog compartimos unos <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/comprar-una-moto-de-segunda-mano\/\">consejos para comprar una moto de segunda mano<\/a>. Y si lo tuyo son los scooters, te explicamos cu\u00e1les son los <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/errores-comprar-scooter-de-segunda-mano\/\">errores al comprar un <em>scooter<\/em> de segunda mano<\/a>. \u00a1Pon en pr\u00e1ctica nuestras recomendaciones!<\/p>\n<h2>\u00bfCu\u00e1l es el mejor seguro para una moto de segunda mano?<\/h2>\n<p>Ya puestos, te orientamos sobre <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/cambio-de-nombre-moto\/\">c\u00f3mo cambiar el nombre de una moto<\/a> y te detallamos los <a href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-gastos-tiene-comprar-una-moto-de-segunda-mano\/\">gastos asociados a la compra de una moto de segunda mano<\/a>: informe de la moto, contrato de compraventa, impuestos, cambio de titularidad, gestor\u00eda, seguro\u2026 En el caso de este \u00faltimo:<\/p>\n<ul>\n<li aria-level=\"1\">Si buscas una p\u00f3liza b\u00e1sica y econ\u00f3mica, nuestro Seguro a Terceros es muy completo, pues incluye las garant\u00edas de Responsabilidad Civil (obligatoria y voluntaria), Riesgos Extraordinarios, Protecci\u00f3n Jur\u00eddica, Reclamaci\u00f3n de Da\u00f1os, Casco y Chaleco Airbag\u2026<\/li>\n<li aria-level=\"1\">\u00bfQuieres un nivel de protecci\u00f3n mayor? En ese caso, puedes elegir un Seguro contra Robo e Incendio.<\/li>\n<li aria-level=\"1\">Y si tu moto de segunda mano u ocasi\u00f3n tiene pocos a\u00f1os y\/o deseas estar bien protegido ante cualquier imprevisto, te aconsejamos contratar un Seguro a Todo Riesgo. Adem\u00e1s de las garant\u00edas incluidas en las otras modalidades, cuenta con la cobertura exclusiva de Da\u00f1os Propios.<\/li>\n<\/ul>\n<p>En AMV ofrecemos <a href=\"https:\/\/www.amv.es\/seguro-moto\/\/\">seguros de moto<\/a> al mejor precio. Puedes elegir la modalidad que mejor se adapte a tus necesidades e incluir en la p\u00f3liza coberturas opcionales como Accidentes del Conductor, Asistencia en Viaje y Equipamiento.<\/p>\n<p>Todo ello 100% <em>online<\/em> y en muy pocos pasos. \u00bfA qu\u00e9 esperas para calcular tu presupuesto sin compromiso? Piensa con el casco y\u2026 \u00a1disfruta de tu moto de segunda mano con seguridad!<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Comprar una moto de segunda mano<\/strong> es una interesante opci\u00f3n cuando no se puede o no se desea adquirir una nueva. De hecho, muchas motos usadas se encuentran en perfectas condiciones de uso. No obstante, antes de formalizar la operaci\u00f3n es importante comprobar el estado y la situaci\u00f3n legal de la moto.<\/p>\n<p>Si no lo tienes claro, no te preocupes: a trav\u00e9s de esta gu\u00eda te explicamos todo lo que debes tener en cuenta en la compra de motos de segunda mano y ocasi\u00f3n. \u00a1Sigue leyendo!<\/p>\n","protected":false},"author":2,"featured_media":5431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[15,14],"class_list":["post-5425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos-amv","tag-moto","tag-segunda-mano"],"acf":{"enlace_1":"","enlace_2":"","enlace_3":"","enlace_4":"","enlace_5":"","enlace_6":"","enlace_7":"","enlace_8":"","enlace_9":"","enlace_10":"","fecha_actualizacion":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV<\/title>\n<meta name=\"description\" content=\"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV\" \/>\n<meta property=\"og:description\" content=\"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog AMV\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T09:29:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T12:43:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"807\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernardo Valad\u00e9s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/\"},\"author\":{\"name\":\"Bernardo Valad\u00e9s\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\"},\"headline\":\"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?\",\"datePublished\":\"2025-03-05T09:29:44+00:00\",\"dateModified\":\"2026-02-12T12:43:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/\"},\"wordCount\":1585,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/que-preguntar-al-comprar-moto-segunda-mano.jpeg\",\"keywords\":[\"Moto\",\"Segunda mano\"],\"articleSection\":[\"Consejos AMV\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/\",\"name\":\"\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/que-preguntar-al-comprar-moto-segunda-mano.jpeg\",\"datePublished\":\"2025-03-05T09:29:44+00:00\",\"dateModified\":\"2026-02-12T12:43:42+00:00\",\"description\":\"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/que-preguntar-al-comprar-moto-segunda-mano.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/que-preguntar-al-comprar-moto-segunda-mano.jpeg\",\"width\":1440,\"height\":807,\"caption\":\"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/que-preguntar-al-comprar-moto-segunda-mano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Noticias AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consejos AMV\",\"item\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/consejos-amv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"name\":\"AMV\",\"description\":\"Blog de Motos y Noticias sobre Seguros\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#organization\",\"name\":\"AMV\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-amv-perfil-noticias.jpg\",\"width\":634,\"height\":634,\"caption\":\"AMV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/#\\\/schema\\\/person\\\/575b5924b7d84a9d9cafef6c40596025\",\"name\":\"Bernardo Valad\u00e9s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg\",\"caption\":\"Bernardo Valad\u00e9s\"},\"description\":\"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/bernardo-valad\u00e9s-6577168a\\\/\"],\"url\":\"https:\\\/\\\/www.amv.es\\\/blog\\\/author\\\/bernardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV","description":"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV","og_description":"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!","og_url":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/","og_site_name":"Blog AMV","article_published_time":"2025-03-05T09:29:44+00:00","article_modified_time":"2026-02-12T12:43:42+00:00","og_image":[{"width":1440,"height":807,"url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg","type":"image\/jpeg"}],"author":"Bernardo Valad\u00e9s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#article","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/"},"author":{"name":"Bernardo Valad\u00e9s","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025"},"headline":"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?","datePublished":"2025-03-05T09:29:44+00:00","dateModified":"2026-02-12T12:43:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/"},"wordCount":1585,"commentCount":0,"publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg","keywords":["Moto","Segunda mano"],"articleSection":["Consejos AMV"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/","url":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/","name":"\u00bfQu\u00e9 preguntar a la hora de comprar una moto de segunda mano? | Blog AMV","isPartOf":{"@id":"https:\/\/www.amv.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#primaryimage"},"image":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg","datePublished":"2025-03-05T09:29:44+00:00","dateModified":"2026-02-12T12:43:42+00:00","description":"Descubre las preguntas clave al comprar una moto de segunda mano y evita sorpresas con los consejos del Blog de AMV \u21e8 \u00a1Inf\u00f3rmate antes de comprar!","breadcrumb":{"@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#primaryimage","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2025\/03\/que-preguntar-al-comprar-moto-segunda-mano.jpeg","width":1440,"height":807,"caption":"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amv.es\/blog\/consejos-amv\/que-preguntar-al-comprar-moto-segunda-mano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Noticias AMV","item":"https:\/\/www.amv.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Consejos AMV","item":"https:\/\/www.amv.es\/blog\/consejos-amv\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 preguntas debes hacer a la hora de comprar una moto de segunda mano?"}]},{"@type":"WebSite","@id":"https:\/\/www.amv.es\/blog\/#website","url":"https:\/\/www.amv.es\/blog\/","name":"AMV","description":"Blog de Motos y Noticias sobre Seguros","publisher":{"@id":"https:\/\/www.amv.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amv.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.amv.es\/blog\/#organization","name":"AMV","url":"https:\/\/www.amv.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/logo-amv-perfil-noticias.jpg","width":634,"height":634,"caption":"AMV"},"image":{"@id":"https:\/\/www.amv.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.amv.es\/blog\/#\/schema\/person\/575b5924b7d84a9d9cafef6c40596025","name":"Bernardo Valad\u00e9s","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","url":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.amv.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-bernardo-valades-autor-amv-scaled-1-96x96.jpg","caption":"Bernardo Valad\u00e9s"},"description":"Periodista socio de la Asociaci\u00f3n de la Prensa de Madrid (APM) y redactor especializado en SEO y GEO, cuenta con una dilatada trayectoria profesional. Apasionado de la F\u00f3rmula 1 y MotoGP, ha trabajado y colaborado en distintas editoriales y medios como Ediciones Aye, Cadena COPE, Grupo Borrmart, Grupo Prisa, P\u00fablico, Grupo V, Revista Tu Moto... Es autor de los libros \u2018Paco Abadal. Biograf\u00eda de un sportsman\u2019 y \u2018La firma Abadal. Aportaciones a la automoci\u00f3n\u2019, ha realizado los estudios de seguridad vial \u2018El colectivo ciclista en Espa\u00f1a\u2019 (Fundaci\u00f3n Mapfre, 2013) y \u2018Profundidad m\u00ednima de los neum\u00e1ticos\u2019 (Continental, 2015), y tambi\u00e9n est\u00e1 especializado en el sector asegurador. Desde 2014 y en la actualidad, redacta art\u00edculos para el blog de AMV.","sameAs":["https:\/\/www.linkedin.com\/in\/bernardo-valad\u00e9s-6577168a\/"],"url":"https:\/\/www.amv.es\/blog\/author\/bernardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/5425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/comments?post=5425"}],"version-history":[{"count":3,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/5425\/revisions"}],"predecessor-version":[{"id":6779,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/posts\/5425\/revisions\/6779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media\/5431"}],"wp:attachment":[{"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/media?parent=5425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/categories?post=5425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amv.es\/blog\/wp-json\/wp\/v2\/tags?post=5425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}